{"id":5380,"date":"2026-06-22T08:49:37","date_gmt":"2026-06-22T06:49:37","guid":{"rendered":"https:\/\/skyfillers.com\/blog\/?p=5380"},"modified":"2026-06-25T08:52:05","modified_gmt":"2026-06-25T06:52:05","slug":"von-malware-bis-passkey-so-gut-kennen-sich-die-deutschen-mit-digitaler-sicherheit-aus","status":"publish","type":"post","link":"https:\/\/skyfillers.com\/blog\/2026\/06\/22\/von-malware-bis-passkey-so-gut-kennen-sich-die-deutschen-mit-digitaler-sicherheit-aus\/","title":{"rendered":"Von Malware bis Passkey \u2013 so gut kennen sich die Deutschen mit digitaler Sicherheit aus"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Cyberangriff, Malware, Phishing oder Passkey \u2013 digitale Sicherheit begegnet vielen Menschen im Alltag. Doch nicht alle k\u00f6nnen zentrale Begriffe auch erkl\u00e4ren. Besonders gel\u00e4ufig ist der Begriff Cyberangriff: Drei Viertel der Deutschen (75 Prozent) geben an, erkl\u00e4ren zu k\u00f6nnen, was damit gemeint ist. Weitere 18 Prozent haben davon geh\u00f6rt, k\u00f6nnen den Begriff aber nicht erkl\u00e4ren. Das sind Ergebnisse einer repr\u00e4sentativen Befragung im Auftrag des Digitalverbands Bitkom unter 1005 Personen in Deutschland ab 16 Jahren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Etwas weniger bekannt sind konkrete Angriffsformen und Schadprogramme. Malware, also Schadsoftware, die etwa Ger\u00e4te infizieren, Daten aussp\u00e4hen oder Systeme lahmlegen kann, ist rund einem Drittel der Deutschen ein Begriff: 35 Prozent haben davon geh\u00f6rt und wissen, was es ist. Weitere 33 Prozent haben den Begriff schon einmal geh\u00f6rt, k\u00f6nnen ihn aber nicht genau erkl\u00e4ren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Etwas bekannter ist Phishing: Dabei werden Menschen beispielsweise \u00fcber gef\u00e4lschte E-Mails oder Webseiten dazu verleitet, sensible Daten wie Passw\u00f6rter oder Zahlungsinformationen preiszugeben. 43 Prozent wissen nach eigenen Angaben, was Phishing ist, weitere 34 Prozent haben zumindest schon einmal davon geh\u00f6rt. \u201eDigitale Sicherheit beginnt mit Verst\u00e4ndnis. Wer Begriffe wie Phishing oder Malware einordnen kann, ist sensibilisierter gegen\u00fcber m\u00f6glichen Risiken\u201c, sagt Felix Kuhlenkamp, Leiter Sicherheit beim Bitkom.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Um digitale Daten und Zug\u00e4nge im Alltag zu sch\u00fctzen, helfen Sicherheitsvorkehrungen wie starke, individuelle Passw\u00f6rter. Passwort-Manager k\u00f6nnen Zugangsdaten verschl\u00fcsselt speichern und dabei unterst\u00fctzen, f\u00fcr verschiedene Dienste sichere Passw\u00f6rter zu nutzen, ohne den \u00dcberblick zu verlieren. Rund die H\u00e4lfte der Deutschen (51 Prozent) kennt den Begriff Passwort-Manager und kann ihn erkl\u00e4ren, weitere 22 Prozent haben zumindest schon davon geh\u00f6rt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zus\u00e4tzlichen Schutz bietet die Zwei-Faktor-Authentifizierung: Dabei wird der Login neben dem Passwort durch einen zweiten Faktor abgesichert, etwa einen Code per App oder eine Best\u00e4tigung auf dem Smartphone. Eine Mehrheit von 60 Prozent wei\u00df nach eigenen Angaben, worum es sich dabei handelt. Ein weiteres Viertel (25 Prozent) hat zumindest schon einmal davon geh\u00f6rt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Weniger bekannt sind Passkeys \u2013 eine neuere, passwortlose Login-Methode, bei der sich Nutzerinnen und Nutzer etwa per Fingerabdruck, Gesichtserkennung oder Ger\u00e4te-PIN anmelden k\u00f6nnen. 28 Prozent der Deutschen k\u00f6nnen erkl\u00e4ren, was mit Passkeys gemeint ist, ein weiteres Drittel (33 Prozent) hat den Begriff zumindest schon einmal geh\u00f6rt. \u201ePasskeys k\u00f6nnen Logins einfacher und sicherer machen, weil kein klassisches Passwort mehr eingegeben werden muss, das gestohlen oder durch Phishing abgegriffen werden k\u00f6nnte\u201c, sagt Kuhlenkamp. \u201eDamit sich solche Technologien durchsetzen, m\u00fcssen sie jedoch verst\u00e4ndlich erkl\u00e4rt und breit nutzbar gemacht werden.\u201c<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cyberangriff, Malware, Phishing oder Passkey \u2013 digitale Sicherheit begegnet vielen Menschen im Alltag. Doch nicht alle k\u00f6nnen zentrale Begriffe auch erkl\u00e4ren. Besonders gel\u00e4ufig ist der Begriff Cyberangriff: Drei Viertel der Deutschen (75 Prozent) geben an, erkl\u00e4ren zu k\u00f6nnen, was damit gemeint ist. Weitere 18 Prozent haben davon geh\u00f6rt, k\u00f6nnen den Begriff aber nicht erkl\u00e4ren. Das &hellip;<\/p>\n","protected":false},"author":2,"featured_media":4664,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[22],"tags":[],"class_list":["post-5380","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Von Malware bis Passkey \u2013 so bekannt ist digitale Sicherheit<\/title>\n<meta name=\"description\" content=\"Cyberangriff, Malware, Phishing, Passkey \u2013 digitale Sicherheit begegnet vielen Menschen im Alltag. Nicht alle k\u00f6nnen die Begriffe erkl\u00e4ren.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skyfillers.com\/blog\/2026\/06\/22\/von-malware-bis-passkey-so-gut-kennen-sich-die-deutschen-mit-digitaler-sicherheit-aus\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Von Malware bis Passkey \u2013 so bekannt ist digitale Sicherheit\" \/>\n<meta property=\"og:description\" content=\"Cyberangriff, Malware, Phishing, Passkey \u2013 digitale Sicherheit begegnet vielen Menschen im Alltag. Nicht alle k\u00f6nnen die Begriffe erkl\u00e4ren.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skyfillers.com\/blog\/2026\/06\/22\/von-malware-bis-passkey-so-gut-kennen-sich-die-deutschen-mit-digitaler-sicherheit-aus\/\" \/>\n<meta property=\"og:site_name\" content=\"Skyfillers Blog\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-22T06:49:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-25T06:52:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2022\/03\/shahadat-rahman-BfrQnKBulYQ-unsplash.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"933\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dirk Siebels\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dirk Siebels\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2026\\\/06\\\/22\\\/von-malware-bis-passkey-so-gut-kennen-sich-die-deutschen-mit-digitaler-sicherheit-aus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2026\\\/06\\\/22\\\/von-malware-bis-passkey-so-gut-kennen-sich-die-deutschen-mit-digitaler-sicherheit-aus\\\/\"},\"author\":{\"name\":\"Dirk Siebels\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/#\\\/schema\\\/person\\\/254623724cef6aaeb7d85429b71aae57\"},\"headline\":\"Von Malware bis Passkey \u2013 so gut kennen sich die Deutschen mit digitaler Sicherheit aus\",\"datePublished\":\"2026-06-22T06:49:37+00:00\",\"dateModified\":\"2026-06-25T06:52:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2026\\\/06\\\/22\\\/von-malware-bis-passkey-so-gut-kennen-sich-die-deutschen-mit-digitaler-sicherheit-aus\\\/\"},\"wordCount\":432,\"image\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2026\\\/06\\\/22\\\/von-malware-bis-passkey-so-gut-kennen-sich-die-deutschen-mit-digitaler-sicherheit-aus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/shahadat-rahman-BfrQnKBulYQ-unsplash.jpg\",\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2026\\\/06\\\/22\\\/von-malware-bis-passkey-so-gut-kennen-sich-die-deutschen-mit-digitaler-sicherheit-aus\\\/\",\"url\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2026\\\/06\\\/22\\\/von-malware-bis-passkey-so-gut-kennen-sich-die-deutschen-mit-digitaler-sicherheit-aus\\\/\",\"name\":\"Von Malware bis Passkey \u2013 so bekannt ist digitale Sicherheit\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2026\\\/06\\\/22\\\/von-malware-bis-passkey-so-gut-kennen-sich-die-deutschen-mit-digitaler-sicherheit-aus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2026\\\/06\\\/22\\\/von-malware-bis-passkey-so-gut-kennen-sich-die-deutschen-mit-digitaler-sicherheit-aus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/shahadat-rahman-BfrQnKBulYQ-unsplash.jpg\",\"datePublished\":\"2026-06-22T06:49:37+00:00\",\"dateModified\":\"2026-06-25T06:52:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/#\\\/schema\\\/person\\\/254623724cef6aaeb7d85429b71aae57\"},\"description\":\"Cyberangriff, Malware, Phishing, Passkey \u2013 digitale Sicherheit begegnet vielen Menschen im Alltag. Nicht alle k\u00f6nnen die Begriffe erkl\u00e4ren.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2026\\\/06\\\/22\\\/von-malware-bis-passkey-so-gut-kennen-sich-die-deutschen-mit-digitaler-sicherheit-aus\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2026\\\/06\\\/22\\\/von-malware-bis-passkey-so-gut-kennen-sich-die-deutschen-mit-digitaler-sicherheit-aus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2026\\\/06\\\/22\\\/von-malware-bis-passkey-so-gut-kennen-sich-die-deutschen-mit-digitaler-sicherheit-aus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/shahadat-rahman-BfrQnKBulYQ-unsplash.jpg\",\"contentUrl\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/shahadat-rahman-BfrQnKBulYQ-unsplash.jpg\",\"width\":1400,\"height\":933,\"caption\":\"Cybersicherheit\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2026\\\/06\\\/22\\\/von-malware-bis-passkey-so-gut-kennen-sich-die-deutschen-mit-digitaler-sicherheit-aus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Von Malware bis Passkey \u2013 so gut kennen sich die Deutschen mit digitaler Sicherheit aus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/\",\"name\":\"Skyfillers Blog\",\"description\":\"Informationen zu E-Mail, Backup, Hosting und mehr.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/#\\\/schema\\\/person\\\/254623724cef6aaeb7d85429b71aae57\",\"name\":\"Dirk Siebels\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g\",\"caption\":\"Dirk Siebels\"},\"url\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/author\\\/dirk\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Von Malware bis Passkey \u2013 so bekannt ist digitale Sicherheit","description":"Cyberangriff, Malware, Phishing, Passkey \u2013 digitale Sicherheit begegnet vielen Menschen im Alltag. Nicht alle k\u00f6nnen die Begriffe erkl\u00e4ren.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skyfillers.com\/blog\/2026\/06\/22\/von-malware-bis-passkey-so-gut-kennen-sich-die-deutschen-mit-digitaler-sicherheit-aus\/","og_locale":"de_DE","og_type":"article","og_title":"Von Malware bis Passkey \u2013 so bekannt ist digitale Sicherheit","og_description":"Cyberangriff, Malware, Phishing, Passkey \u2013 digitale Sicherheit begegnet vielen Menschen im Alltag. Nicht alle k\u00f6nnen die Begriffe erkl\u00e4ren.","og_url":"https:\/\/skyfillers.com\/blog\/2026\/06\/22\/von-malware-bis-passkey-so-gut-kennen-sich-die-deutschen-mit-digitaler-sicherheit-aus\/","og_site_name":"Skyfillers Blog","article_published_time":"2026-06-22T06:49:37+00:00","article_modified_time":"2026-06-25T06:52:05+00:00","og_image":[{"width":1400,"height":933,"url":"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2022\/03\/shahadat-rahman-BfrQnKBulYQ-unsplash.jpg","type":"image\/jpeg"}],"author":"Dirk Siebels","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Dirk Siebels","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/skyfillers.com\/blog\/2026\/06\/22\/von-malware-bis-passkey-so-gut-kennen-sich-die-deutschen-mit-digitaler-sicherheit-aus\/#article","isPartOf":{"@id":"https:\/\/skyfillers.com\/blog\/2026\/06\/22\/von-malware-bis-passkey-so-gut-kennen-sich-die-deutschen-mit-digitaler-sicherheit-aus\/"},"author":{"name":"Dirk Siebels","@id":"https:\/\/skyfillers.com\/blog\/#\/schema\/person\/254623724cef6aaeb7d85429b71aae57"},"headline":"Von Malware bis Passkey \u2013 so gut kennen sich die Deutschen mit digitaler Sicherheit aus","datePublished":"2026-06-22T06:49:37+00:00","dateModified":"2026-06-25T06:52:05+00:00","mainEntityOfPage":{"@id":"https:\/\/skyfillers.com\/blog\/2026\/06\/22\/von-malware-bis-passkey-so-gut-kennen-sich-die-deutschen-mit-digitaler-sicherheit-aus\/"},"wordCount":432,"image":{"@id":"https:\/\/skyfillers.com\/blog\/2026\/06\/22\/von-malware-bis-passkey-so-gut-kennen-sich-die-deutschen-mit-digitaler-sicherheit-aus\/#primaryimage"},"thumbnailUrl":"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2022\/03\/shahadat-rahman-BfrQnKBulYQ-unsplash.jpg","inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/skyfillers.com\/blog\/2026\/06\/22\/von-malware-bis-passkey-so-gut-kennen-sich-die-deutschen-mit-digitaler-sicherheit-aus\/","url":"https:\/\/skyfillers.com\/blog\/2026\/06\/22\/von-malware-bis-passkey-so-gut-kennen-sich-die-deutschen-mit-digitaler-sicherheit-aus\/","name":"Von Malware bis Passkey \u2013 so bekannt ist digitale Sicherheit","isPartOf":{"@id":"https:\/\/skyfillers.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skyfillers.com\/blog\/2026\/06\/22\/von-malware-bis-passkey-so-gut-kennen-sich-die-deutschen-mit-digitaler-sicherheit-aus\/#primaryimage"},"image":{"@id":"https:\/\/skyfillers.com\/blog\/2026\/06\/22\/von-malware-bis-passkey-so-gut-kennen-sich-die-deutschen-mit-digitaler-sicherheit-aus\/#primaryimage"},"thumbnailUrl":"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2022\/03\/shahadat-rahman-BfrQnKBulYQ-unsplash.jpg","datePublished":"2026-06-22T06:49:37+00:00","dateModified":"2026-06-25T06:52:05+00:00","author":{"@id":"https:\/\/skyfillers.com\/blog\/#\/schema\/person\/254623724cef6aaeb7d85429b71aae57"},"description":"Cyberangriff, Malware, Phishing, Passkey \u2013 digitale Sicherheit begegnet vielen Menschen im Alltag. Nicht alle k\u00f6nnen die Begriffe erkl\u00e4ren.","breadcrumb":{"@id":"https:\/\/skyfillers.com\/blog\/2026\/06\/22\/von-malware-bis-passkey-so-gut-kennen-sich-die-deutschen-mit-digitaler-sicherheit-aus\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skyfillers.com\/blog\/2026\/06\/22\/von-malware-bis-passkey-so-gut-kennen-sich-die-deutschen-mit-digitaler-sicherheit-aus\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skyfillers.com\/blog\/2026\/06\/22\/von-malware-bis-passkey-so-gut-kennen-sich-die-deutschen-mit-digitaler-sicherheit-aus\/#primaryimage","url":"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2022\/03\/shahadat-rahman-BfrQnKBulYQ-unsplash.jpg","contentUrl":"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2022\/03\/shahadat-rahman-BfrQnKBulYQ-unsplash.jpg","width":1400,"height":933,"caption":"Cybersicherheit"},{"@type":"BreadcrumbList","@id":"https:\/\/skyfillers.com\/blog\/2026\/06\/22\/von-malware-bis-passkey-so-gut-kennen-sich-die-deutschen-mit-digitaler-sicherheit-aus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/skyfillers.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Von Malware bis Passkey \u2013 so gut kennen sich die Deutschen mit digitaler Sicherheit aus"}]},{"@type":"WebSite","@id":"https:\/\/skyfillers.com\/blog\/#website","url":"https:\/\/skyfillers.com\/blog\/","name":"Skyfillers Blog","description":"Informationen zu E-Mail, Backup, Hosting und mehr.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skyfillers.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/skyfillers.com\/blog\/#\/schema\/person\/254623724cef6aaeb7d85429b71aae57","name":"Dirk Siebels","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g","caption":"Dirk Siebels"},"url":"https:\/\/skyfillers.com\/blog\/author\/dirk\/"}]}},"_links":{"self":[{"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/posts\/5380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/comments?post=5380"}],"version-history":[{"count":1,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/posts\/5380\/revisions"}],"predecessor-version":[{"id":5381,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/posts\/5380\/revisions\/5381"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/media\/4664"}],"wp:attachment":[{"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/media?parent=5380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/categories?post=5380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/tags?post=5380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}