{"id":4935,"date":"2023-05-16T19:07:19","date_gmt":"2023-05-16T17:07:19","guid":{"rendered":"https:\/\/skyfillers.com\/blog\/?p=4935"},"modified":"2023-06-01T19:10:12","modified_gmt":"2023-06-01T17:10:12","slug":"cloud-nutzung-wird-rasant-zunehmen","status":"publish","type":"post","link":"https:\/\/skyfillers.com\/blog\/2023\/05\/16\/cloud-nutzung-wird-rasant-zunehmen\/","title":{"rendered":"Cloud-Nutzung wird rasant zunehmen"},"content":{"rendered":"\n<p>Cloud Computing hat sich in Deutschland etabliert und steht vor einem rasanten Wachstum. In f\u00fcnf Jahren wollen 56 Prozent aller Unternehmen mehr als die H\u00e4lfte ihrer IT-Anwendungen aus der Cloud betreiben. Aktuell liegt der Anteil gerade einmal bei 15 Prozent. Jedes zweite Unternehmen (54 Prozent) will in diesem Jahr in Cloud-L\u00f6sungen investieren, zwei Drittel (69 Prozent) planen dies f\u00fcr 2024 oder sp\u00e4ter. Derzeit nutzen 89 Prozent <a href=\"https:\/\/skyfillers.com\/blog\/2022\/04\/01\/cloud-computing-besser-interne-alternativen\/\">Cloud Computing<\/a>, weitere 8 Prozent planen oder diskutieren das. Nur f\u00fcr 3 Prozent ist die Cloud kein Thema.<\/p>\n\n\n\n<p>Das sind Ergebnisse einer repr\u00e4sentativen Befragung von 554 Unternehmen ab 20 Besch\u00e4ftigten aus allen Wirtschaftsbereichen im Auftrag des Digitalverbands Bitkom. \u201eSchon heute nutzen praktisch alle Unternehmen Cloud-Anwendungen. Die Intensit\u00e4t der Nutzung wird in den n\u00e4chsten Jahren aber stark zunehmen. Cloud ist das Neue Normal der digitalen Welt\u201c, sagt Bitkom-Hauptgesch\u00e4ftsf\u00fchrer Dr. Bernhard Rohleder. \u201eGleichzeitig gilt aber auch: Die Unternehmen werden zumindest mittelfristig nicht alle IT-Anwendungen in die Cloud verlagern.\u201c<\/p>\n\n\n\n<p>Jedes neunte Unternehmen, das die Cloud nutzt, hat eine \u201eCloud only\u201c-Strategie. Das hei\u00dft, Cloud Computing wird f\u00fcr alle Anwendungen und Systeme genutzt und bestehende L\u00f6sungen werden in die Cloud \u00fcberf\u00fchrt. Weitere 36 Prozent setzen auf \u201eCloud first\u201c, das bedeutet, bei neuen Projekten werden bevorzugt Cloud-L\u00f6sungen <a href=\"https:\/\/skyfillers.com\/blog\/2023\/01\/09\/hybrid-cloud-digitalisierung\/\">verwendet<\/a> und bestehende Anwendungen bei Bedarf in die Cloud umgezogen. F\u00fcr 35 Prozent gilt \u201eCloud too\u201c, also die zumindest teilweise Erg\u00e4nzung bestehender IT-L\u00f6sungen um Cloud-Anwendungen. \u201eFast die H\u00e4lfte aller Unternehmen bevorzugt bei neuen IT-Projekten Cloud-L\u00f6sungen. Das ist ein klares Signal an die Software-Anbieter, die ihr Angebot teilweise noch anpassen m\u00fcssen\u201c, so Rohleder.<\/p>\n\n\n\n<p>Schon heute nutzen Unternehmen die unterschiedlichsten Cloud-Angebote. Am h\u00e4ufigsten verwendet wird Speicherplatz in der Cloud (92 Prozent), dahinter folgen Webconferencing (76 Prozent), allgemeine Rechenleistung f\u00fcr unterschiedlichste Anwendungen sowie Office-Software (je 73 Prozent) und Software f\u00fcr Personal, Buchhaltung und Finanzplanung (72 Prozent). Cloudbasierte Datenbanken nutzen 60 Prozent, ERP-Systeme 30 Prozent. Aber auch spezielle Anwendungen wie IoT- (37 Prozent) oder KI-Dienste (32 Prozent) kommen aus der Cloud.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cloud soll Kosten sparen und nachhaltiger machen<\/h2>\n\n\n\n<p>Wichtigstes Ziel bei ihren Cloud-Aktivit\u00e4ten ist f\u00fcr die Unternehmen die Reduzierung von Kosten (64 Prozent) sowie die Reduzierung der CO2-Emissionen (63 Prozent). Eine Mehrheit von je 57 Prozent will zudem IT-Anwendungen auf Plattformen und Software-as-a-Service umstellen sowie die IT-Sicherheit erh\u00f6hen. Weitere wichtige Ziele sind der Aufbau von Plattformen zur Kooperation mit Dritten (49 Prozent), die Digitalisierung interner Prozesse (46 Prozent) und die Entwicklung innovativer Produkte oder Dienste (43 Prozent). 39 Prozent sehen zudem einen Ausweg aus der bestehenden Hardware-Knappheit, die einen Ausbau eigener Rechenzentren behindert hat, 38 Prozent versprechen sich durch die Cloud Zugang zu innovativen Technologien wie IoT oder KI.<\/p>\n\n\n\n<p>Auch wenn viele Unternehmen hoffen, durch Cloud-L\u00f6sungen einen Beitrag zum Klimaschutz zu leisten, so sehen sie in diesem Bereich neben Licht auch Schatten. 57 Prozent aller Unternehmen sind der Meinung, dass sich durch Cloud Computing Energie und Ressourcen sparen lassen. 59 Prozent meinen, durch Cloud Computing werde die Erstellung von Nachhaltigkeits-Reportings vereinfacht. Auf der anderen Seite beklagen 48 Prozent aber auch, dass der Energie- und Ressourcenverbrauch beim Cloud Computing zu intransparent ist und drei Viertel sagen, dass Cloud Computing durch die einfache Skalierbarkeit dazu f\u00fchrt, dass Software immer ressourcenhungriger programmiert wird. \u201eCloud Computing kann Unternehmen dabei helfen, nachhaltiger zu werden. Dabei k\u00f6nnen Initiativen wie Green Coding daf\u00fcr sorgen, dass die Bereitstellung von Rechenleistung und Speicherplatz per Mausklick nicht dazu f\u00fchrt, dass der Ressourcenverbrauch und damit auch die Kosten aus dem Blick geraten\u201c, sagt Rohleder.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Cloud-Hemmnis Nummer eins ist der Fachkr\u00e4ftemangel<\/h2>\n\n\n\n<p>Bei der Umsetzung von Cloud-Projekten stehen die Unternehmen vor vielen H\u00fcrden. Diese H\u00fcrden bestehen im Unternehmen selbst, werden von au\u00dfen gesetzt oder aber betreffen grunds\u00e4tzliche Sicherheitsfragen. Die gr\u00f6\u00dfte Bremse f\u00fcr den Cloud-Markt ist der Mangel an qualifiziertem <a href=\"https:\/\/www.it-daily.net\/it-management\/cloud-computing\/it-fachkraeftemangel-die-cloud-als-loesung\" target=\"_blank\" rel=\"noreferrer noopener\">Personal<\/a> (65 Prozent). Weitere bedeutende unternehmensinterne Hemmnisse sind fehlende Zeit (53 Prozent), zu komplexe Migrations-Aufgaben (52 Prozent) und ein zu hoher Investitionsbedarf (50 Prozent). Jeweils 42 Prozent werden durch Widerstand im eigenen Unternehmen sowie fehlende externe Beratung bei ihren Cloud-Vorhaben gehemmt. Nur 35 Prozent geben an, dass ihnen der wirtschaftliche Nutzen unklar ist.<\/p>\n\n\n\n<p>Hindernisse f\u00fcr Cloud-Projekte sind zudem zu hohe Anforderungen an die IT-Sicherheit (59 Prozent) und an den Datenschutz (56 Prozent) sowie regulatorische Bedingungen (51 Prozent), etwa in bestimmten Branchen wie der Finanzindustrie oder im Gesundheitswesen. Rund zwei Drittel (64 Prozent) bef\u00fcrchten unberechtigten Zugriff auf sensible Daten in der Cloud, 45 Prozent haben Angst vor dem Verlust von Daten. \u201eDer Umstieg auf die Cloud kann die IT-Sicherheit in Unternehmen deutlich erh\u00f6hen, insbesondere f\u00fcr kleine und mittelst\u00e4ndische Unternehmen, die sich keine gro\u00dfe IT-Abteilung leisten k\u00f6nnen\u201c, so Rohleder.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cloud Computing hat sich in Deutschland etabliert und steht vor einem rasanten Wachstum. In f\u00fcnf Jahren wollen 56 Prozent aller Unternehmen mehr als die H\u00e4lfte ihrer IT-Anwendungen aus der Cloud betreiben. Aktuell liegt der Anteil gerade einmal bei 15 Prozent. Jedes zweite Unternehmen (54 Prozent) will in diesem Jahr in Cloud-L\u00f6sungen investieren, zwei Drittel (69 &hellip;<\/p>\n","protected":false},"author":2,"featured_media":4692,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[22],"tags":[],"class_list":["post-4935","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cloud-Nutzung wird rasant zunehmen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skyfillers.com\/blog\/2023\/05\/16\/cloud-nutzung-wird-rasant-zunehmen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cloud-Nutzung wird rasant zunehmen\" \/>\n<meta property=\"og:description\" content=\"Cloud Computing hat sich in Deutschland etabliert und steht vor einem rasanten Wachstum. In f\u00fcnf Jahren wollen 56 Prozent aller Unternehmen mehr als die H\u00e4lfte ihrer IT-Anwendungen aus der Cloud betreiben. Aktuell liegt der Anteil gerade einmal bei 15 Prozent. Jedes zweite Unternehmen (54 Prozent) will in diesem Jahr in Cloud-L\u00f6sungen investieren, zwei Drittel (69 &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skyfillers.com\/blog\/2023\/05\/16\/cloud-nutzung-wird-rasant-zunehmen\/\" \/>\n<meta property=\"og:site_name\" content=\"Skyfillers Blog\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-16T17:07:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-01T17:10:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2022\/04\/taylor-vick-M5tzZtFCOfs-unsplash.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"785\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dirk Siebels\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dirk Siebels\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2023\\\/05\\\/16\\\/cloud-nutzung-wird-rasant-zunehmen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2023\\\/05\\\/16\\\/cloud-nutzung-wird-rasant-zunehmen\\\/\"},\"author\":{\"name\":\"Dirk Siebels\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/#\\\/schema\\\/person\\\/254623724cef6aaeb7d85429b71aae57\"},\"headline\":\"Cloud-Nutzung wird rasant zunehmen\",\"datePublished\":\"2023-05-16T17:07:19+00:00\",\"dateModified\":\"2023-06-01T17:10:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2023\\\/05\\\/16\\\/cloud-nutzung-wird-rasant-zunehmen\\\/\"},\"wordCount\":748,\"image\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2023\\\/05\\\/16\\\/cloud-nutzung-wird-rasant-zunehmen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/taylor-vick-M5tzZtFCOfs-unsplash.jpg\",\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2023\\\/05\\\/16\\\/cloud-nutzung-wird-rasant-zunehmen\\\/\",\"url\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2023\\\/05\\\/16\\\/cloud-nutzung-wird-rasant-zunehmen\\\/\",\"name\":\"Cloud-Nutzung wird rasant zunehmen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2023\\\/05\\\/16\\\/cloud-nutzung-wird-rasant-zunehmen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2023\\\/05\\\/16\\\/cloud-nutzung-wird-rasant-zunehmen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/taylor-vick-M5tzZtFCOfs-unsplash.jpg\",\"datePublished\":\"2023-05-16T17:07:19+00:00\",\"dateModified\":\"2023-06-01T17:10:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/#\\\/schema\\\/person\\\/254623724cef6aaeb7d85429b71aae57\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2023\\\/05\\\/16\\\/cloud-nutzung-wird-rasant-zunehmen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2023\\\/05\\\/16\\\/cloud-nutzung-wird-rasant-zunehmen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2023\\\/05\\\/16\\\/cloud-nutzung-wird-rasant-zunehmen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/taylor-vick-M5tzZtFCOfs-unsplash.jpg\",\"contentUrl\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/taylor-vick-M5tzZtFCOfs-unsplash.jpg\",\"width\":1400,\"height\":785,\"caption\":\"cloud computing\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2023\\\/05\\\/16\\\/cloud-nutzung-wird-rasant-zunehmen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cloud-Nutzung wird rasant zunehmen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/\",\"name\":\"Skyfillers Blog\",\"description\":\"Informationen zu E-Mail, Backup, Hosting und mehr.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/#\\\/schema\\\/person\\\/254623724cef6aaeb7d85429b71aae57\",\"name\":\"Dirk Siebels\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g\",\"caption\":\"Dirk Siebels\"},\"url\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/author\\\/dirk\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cloud-Nutzung wird rasant zunehmen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skyfillers.com\/blog\/2023\/05\/16\/cloud-nutzung-wird-rasant-zunehmen\/","og_locale":"de_DE","og_type":"article","og_title":"Cloud-Nutzung wird rasant zunehmen","og_description":"Cloud Computing hat sich in Deutschland etabliert und steht vor einem rasanten Wachstum. In f\u00fcnf Jahren wollen 56 Prozent aller Unternehmen mehr als die H\u00e4lfte ihrer IT-Anwendungen aus der Cloud betreiben. Aktuell liegt der Anteil gerade einmal bei 15 Prozent. Jedes zweite Unternehmen (54 Prozent) will in diesem Jahr in Cloud-L\u00f6sungen investieren, zwei Drittel (69 &hellip;","og_url":"https:\/\/skyfillers.com\/blog\/2023\/05\/16\/cloud-nutzung-wird-rasant-zunehmen\/","og_site_name":"Skyfillers Blog","article_published_time":"2023-05-16T17:07:19+00:00","article_modified_time":"2023-06-01T17:10:12+00:00","og_image":[{"width":1400,"height":785,"url":"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2022\/04\/taylor-vick-M5tzZtFCOfs-unsplash.jpg","type":"image\/jpeg"}],"author":"Dirk Siebels","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Dirk Siebels","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/skyfillers.com\/blog\/2023\/05\/16\/cloud-nutzung-wird-rasant-zunehmen\/#article","isPartOf":{"@id":"https:\/\/skyfillers.com\/blog\/2023\/05\/16\/cloud-nutzung-wird-rasant-zunehmen\/"},"author":{"name":"Dirk Siebels","@id":"https:\/\/skyfillers.com\/blog\/#\/schema\/person\/254623724cef6aaeb7d85429b71aae57"},"headline":"Cloud-Nutzung wird rasant zunehmen","datePublished":"2023-05-16T17:07:19+00:00","dateModified":"2023-06-01T17:10:12+00:00","mainEntityOfPage":{"@id":"https:\/\/skyfillers.com\/blog\/2023\/05\/16\/cloud-nutzung-wird-rasant-zunehmen\/"},"wordCount":748,"image":{"@id":"https:\/\/skyfillers.com\/blog\/2023\/05\/16\/cloud-nutzung-wird-rasant-zunehmen\/#primaryimage"},"thumbnailUrl":"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2022\/04\/taylor-vick-M5tzZtFCOfs-unsplash.jpg","inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/skyfillers.com\/blog\/2023\/05\/16\/cloud-nutzung-wird-rasant-zunehmen\/","url":"https:\/\/skyfillers.com\/blog\/2023\/05\/16\/cloud-nutzung-wird-rasant-zunehmen\/","name":"Cloud-Nutzung wird rasant zunehmen","isPartOf":{"@id":"https:\/\/skyfillers.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skyfillers.com\/blog\/2023\/05\/16\/cloud-nutzung-wird-rasant-zunehmen\/#primaryimage"},"image":{"@id":"https:\/\/skyfillers.com\/blog\/2023\/05\/16\/cloud-nutzung-wird-rasant-zunehmen\/#primaryimage"},"thumbnailUrl":"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2022\/04\/taylor-vick-M5tzZtFCOfs-unsplash.jpg","datePublished":"2023-05-16T17:07:19+00:00","dateModified":"2023-06-01T17:10:12+00:00","author":{"@id":"https:\/\/skyfillers.com\/blog\/#\/schema\/person\/254623724cef6aaeb7d85429b71aae57"},"breadcrumb":{"@id":"https:\/\/skyfillers.com\/blog\/2023\/05\/16\/cloud-nutzung-wird-rasant-zunehmen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skyfillers.com\/blog\/2023\/05\/16\/cloud-nutzung-wird-rasant-zunehmen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skyfillers.com\/blog\/2023\/05\/16\/cloud-nutzung-wird-rasant-zunehmen\/#primaryimage","url":"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2022\/04\/taylor-vick-M5tzZtFCOfs-unsplash.jpg","contentUrl":"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2022\/04\/taylor-vick-M5tzZtFCOfs-unsplash.jpg","width":1400,"height":785,"caption":"cloud computing"},{"@type":"BreadcrumbList","@id":"https:\/\/skyfillers.com\/blog\/2023\/05\/16\/cloud-nutzung-wird-rasant-zunehmen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/skyfillers.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Cloud-Nutzung wird rasant zunehmen"}]},{"@type":"WebSite","@id":"https:\/\/skyfillers.com\/blog\/#website","url":"https:\/\/skyfillers.com\/blog\/","name":"Skyfillers Blog","description":"Informationen zu E-Mail, Backup, Hosting und mehr.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skyfillers.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/skyfillers.com\/blog\/#\/schema\/person\/254623724cef6aaeb7d85429b71aae57","name":"Dirk Siebels","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g","caption":"Dirk Siebels"},"url":"https:\/\/skyfillers.com\/blog\/author\/dirk\/"}]}},"_links":{"self":[{"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/posts\/4935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/comments?post=4935"}],"version-history":[{"count":1,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/posts\/4935\/revisions"}],"predecessor-version":[{"id":4936,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/posts\/4935\/revisions\/4936"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/media\/4692"}],"wp:attachment":[{"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/media?parent=4935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/categories?post=4935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/tags?post=4935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}