{"id":4321,"date":"2021-02-01T07:39:00","date_gmt":"2021-02-01T06:39:00","guid":{"rendered":"https:\/\/www.skyfillers.com\/blog\/?p=4321"},"modified":"2021-02-01T10:14:55","modified_gmt":"2021-02-01T09:14:55","slug":"datensicherheit-internet-vertrauen-steigt-langsam","status":"publish","type":"post","link":"https:\/\/skyfillers.com\/blog\/2021\/02\/01\/datensicherheit-internet-vertrauen-steigt-langsam\/","title":{"rendered":"Datensicherheit im Internet: Vertrauen der Nutzer steigt langsam"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Das Vertrauen in die Datensicherheit im Internet steigt langsam, aber stetig. Eine aktuelle Umfrage zeigt, dass 29 Prozent der Internetnutzer der Meinung sind, dass ihre pers\u00f6nlichen Daten im online sicher sind. Im Jahr 2019 lag der Wert noch bei 27 Prozent, f\u00fcnf Jahre zuvor sogar bei nur 14 Prozent. Allerdings finden 68 Prozent der Internetnutzer noch immer, dass ihre pers\u00f6nlichen Daten im Internet nicht sicher sind.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr die Umfrage zur Datensicherheit wurden 1016 Internetnutzer in Deutschland befragt. Durchgef\u00fchrt wurde die Studie im Auftrag des Digitalverbands Bitkom. Die Ergebnisse d\u00fcrften zumindest einen kleinen Einfluss auf die Debatte um das <a href=\"https:\/\/netzpolitik.org\/2020\/it-sicherheitsgesetz-2-0-innenministerium-setzt-zum-voreiligen-endspurt-an\/\" target=\"_blank\" rel=\"noreferrer noopener\">IT-Sicherheitsgesetz 2.0<\/a> auswirken. Mit diesem Gesetz sollen die Sicherheit f\u00fcr Verbraucher, kritische Infrastrukturen und die Bundesverwaltung gesteigert werden.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Unter anderem sieht der aktuelle Entwurf des Gesetzes vor, dass das Bundesamt f\u00fcr Sicherheit in der Informationstechnik personell und finanziell besser ausgestattet werden soll. Allerdings betont Bitkom-Pr\u00e4sident Achim Berg, dass beh\u00f6rdliche Befugnisse und Eingriffsrechte sachlich begr\u00fcndbar und klar an den Schutzzielen ausgerichtet sein m\u00fcssten. \u201eBlo\u00dfe Kompetenzausweitungen f\u00fcr Beh\u00f6rden werden unsere kritischen Infrastrukturen nicht sicherer machen.\u201c Speziell f\u00fcr die Betreiber von Telekommunikationsnetzen w\u00fcrden sich aus dem derzeitigen Entwurf zudem gro\u00dfe Unsicherheiten ergeben, betont Berg.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Vorgaben f\u00fcr k\u00fcnftige Sicherheitsanforderungen an Telekommunikationsnetze erg\u00e4nzen das geplante Telekommunikationsmodernisierungsgesetz, das ebenfalls aktuell debattiert wird. F\u00fcr den weiteren Ausbau der entsprechenden Infrastruktur sollen die rechtlichen H\u00fcrden gesenkt werden. Zudem soll die Mitnutzung von Infrastrukturen leichter werden.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zugleich sind allerdings auch neue Informationspflichten in der Vorlage vorgesehen. Staatliche Eingriffe in den Netzausbau sind ebenso m\u00f6glich. Mittel- bis langfristige Planungen werden f\u00fcr die betroffenen Unternehmen somit wesentlich komplexer. Der Ausbau im Festnetz und Mobilfunk h\u00e4nge von vielen Faktoren ab, sagt Berg zu diesem Thema. Dabei spielen die Genehmigungslage und die Unterst\u00fctzung durch die Kommunen vor Ort eine entscheidende Rolle. \u201eWer ein Recht auf schnelles Internet umsetzen will, der muss zun\u00e4chst geeignete und verl\u00e4ssliche Verfahren schaffen, mit denen die daf\u00fcr ben\u00f6tigten Kapazit\u00e4ten aufgebaut werden k\u00f6nnen\u201c, meint der Bitkom-Pr\u00e4sident.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Vertrauen in die Datensicherheit im Internet steigt langsam, aber stetig. Eine aktuelle Umfrage zeigt, dass 29 Prozent der Internetnutzer der Meinung sind, dass ihre pers\u00f6nlichen Daten im online sicher sind. Im Jahr 2019 lag der Wert noch bei 27 Prozent, f\u00fcnf Jahre zuvor sogar bei nur 14 Prozent. Allerdings finden 68 Prozent der Internetnutzer &hellip;<\/p>\n","protected":false},"author":2,"featured_media":4320,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[22],"tags":[],"class_list":["post-4321","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Datensicherheit im Internet: Vertrauen der Nutzer steigt langsam<\/title>\n<meta name=\"description\" content=\"Eine aktuelle Umfrage zeigt, dass 29 Prozent der Internetnutzer der Meinung sind, dass ihre pers\u00f6nlichen Daten im online sicher sind.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skyfillers.com\/blog\/2021\/02\/01\/datensicherheit-internet-vertrauen-steigt-langsam\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datensicherheit im Internet: Vertrauen der Nutzer steigt langsam\" \/>\n<meta property=\"og:description\" content=\"Eine aktuelle Umfrage zeigt, dass 29 Prozent der Internetnutzer der Meinung sind, dass ihre pers\u00f6nlichen Daten im online sicher sind.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skyfillers.com\/blog\/2021\/02\/01\/datensicherheit-internet-vertrauen-steigt-langsam\/\" \/>\n<meta property=\"og:site_name\" content=\"Skyfillers Blog\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-01T06:39:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-02-01T09:14:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2021\/01\/glenn-carstens-peters-npxXWgQ33ZQ-unsplash.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1064\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dirk Siebels\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dirk Siebels\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2021\\\/02\\\/01\\\/datensicherheit-internet-vertrauen-steigt-langsam\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2021\\\/02\\\/01\\\/datensicherheit-internet-vertrauen-steigt-langsam\\\/\"},\"author\":{\"name\":\"Dirk Siebels\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/#\\\/schema\\\/person\\\/254623724cef6aaeb7d85429b71aae57\"},\"headline\":\"Datensicherheit im Internet: Vertrauen der Nutzer steigt langsam\",\"datePublished\":\"2021-02-01T06:39:00+00:00\",\"dateModified\":\"2021-02-01T09:14:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2021\\\/02\\\/01\\\/datensicherheit-internet-vertrauen-steigt-langsam\\\/\"},\"wordCount\":354,\"image\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2021\\\/02\\\/01\\\/datensicherheit-internet-vertrauen-steigt-langsam\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/glenn-carstens-peters-npxXWgQ33ZQ-unsplash.jpg\",\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2021\\\/02\\\/01\\\/datensicherheit-internet-vertrauen-steigt-langsam\\\/\",\"url\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2021\\\/02\\\/01\\\/datensicherheit-internet-vertrauen-steigt-langsam\\\/\",\"name\":\"Datensicherheit im Internet: Vertrauen der Nutzer steigt langsam\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2021\\\/02\\\/01\\\/datensicherheit-internet-vertrauen-steigt-langsam\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2021\\\/02\\\/01\\\/datensicherheit-internet-vertrauen-steigt-langsam\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/glenn-carstens-peters-npxXWgQ33ZQ-unsplash.jpg\",\"datePublished\":\"2021-02-01T06:39:00+00:00\",\"dateModified\":\"2021-02-01T09:14:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/#\\\/schema\\\/person\\\/254623724cef6aaeb7d85429b71aae57\"},\"description\":\"Eine aktuelle Umfrage zeigt, dass 29 Prozent der Internetnutzer der Meinung sind, dass ihre pers\u00f6nlichen Daten im online sicher sind.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2021\\\/02\\\/01\\\/datensicherheit-internet-vertrauen-steigt-langsam\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2021\\\/02\\\/01\\\/datensicherheit-internet-vertrauen-steigt-langsam\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2021\\\/02\\\/01\\\/datensicherheit-internet-vertrauen-steigt-langsam\\\/#primaryimage\",\"url\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/glenn-carstens-peters-npxXWgQ33ZQ-unsplash.jpg\",\"contentUrl\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/glenn-carstens-peters-npxXWgQ33ZQ-unsplash.jpg\",\"width\":1600,\"height\":1064,\"caption\":\"Datensicherheit im Internet: Vertrauen der Nutzer steigt langsam\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2021\\\/02\\\/01\\\/datensicherheit-internet-vertrauen-steigt-langsam\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Datensicherheit im Internet: Vertrauen der Nutzer steigt langsam\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/\",\"name\":\"Skyfillers Blog\",\"description\":\"Informationen zu E-Mail, Backup, Hosting und mehr.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/#\\\/schema\\\/person\\\/254623724cef6aaeb7d85429b71aae57\",\"name\":\"Dirk Siebels\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g\",\"caption\":\"Dirk Siebels\"},\"url\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/author\\\/dirk\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datensicherheit im Internet: Vertrauen der Nutzer steigt langsam","description":"Eine aktuelle Umfrage zeigt, dass 29 Prozent der Internetnutzer der Meinung sind, dass ihre pers\u00f6nlichen Daten im online sicher sind.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skyfillers.com\/blog\/2021\/02\/01\/datensicherheit-internet-vertrauen-steigt-langsam\/","og_locale":"de_DE","og_type":"article","og_title":"Datensicherheit im Internet: Vertrauen der Nutzer steigt langsam","og_description":"Eine aktuelle Umfrage zeigt, dass 29 Prozent der Internetnutzer der Meinung sind, dass ihre pers\u00f6nlichen Daten im online sicher sind.","og_url":"https:\/\/skyfillers.com\/blog\/2021\/02\/01\/datensicherheit-internet-vertrauen-steigt-langsam\/","og_site_name":"Skyfillers Blog","article_published_time":"2021-02-01T06:39:00+00:00","article_modified_time":"2021-02-01T09:14:55+00:00","og_image":[{"width":1600,"height":1064,"url":"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2021\/01\/glenn-carstens-peters-npxXWgQ33ZQ-unsplash.jpg","type":"image\/jpeg"}],"author":"Dirk Siebels","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Dirk Siebels","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/skyfillers.com\/blog\/2021\/02\/01\/datensicherheit-internet-vertrauen-steigt-langsam\/#article","isPartOf":{"@id":"https:\/\/skyfillers.com\/blog\/2021\/02\/01\/datensicherheit-internet-vertrauen-steigt-langsam\/"},"author":{"name":"Dirk Siebels","@id":"https:\/\/skyfillers.com\/blog\/#\/schema\/person\/254623724cef6aaeb7d85429b71aae57"},"headline":"Datensicherheit im Internet: Vertrauen der Nutzer steigt langsam","datePublished":"2021-02-01T06:39:00+00:00","dateModified":"2021-02-01T09:14:55+00:00","mainEntityOfPage":{"@id":"https:\/\/skyfillers.com\/blog\/2021\/02\/01\/datensicherheit-internet-vertrauen-steigt-langsam\/"},"wordCount":354,"image":{"@id":"https:\/\/skyfillers.com\/blog\/2021\/02\/01\/datensicherheit-internet-vertrauen-steigt-langsam\/#primaryimage"},"thumbnailUrl":"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2021\/01\/glenn-carstens-peters-npxXWgQ33ZQ-unsplash.jpg","inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/skyfillers.com\/blog\/2021\/02\/01\/datensicherheit-internet-vertrauen-steigt-langsam\/","url":"https:\/\/skyfillers.com\/blog\/2021\/02\/01\/datensicherheit-internet-vertrauen-steigt-langsam\/","name":"Datensicherheit im Internet: Vertrauen der Nutzer steigt langsam","isPartOf":{"@id":"https:\/\/skyfillers.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skyfillers.com\/blog\/2021\/02\/01\/datensicherheit-internet-vertrauen-steigt-langsam\/#primaryimage"},"image":{"@id":"https:\/\/skyfillers.com\/blog\/2021\/02\/01\/datensicherheit-internet-vertrauen-steigt-langsam\/#primaryimage"},"thumbnailUrl":"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2021\/01\/glenn-carstens-peters-npxXWgQ33ZQ-unsplash.jpg","datePublished":"2021-02-01T06:39:00+00:00","dateModified":"2021-02-01T09:14:55+00:00","author":{"@id":"https:\/\/skyfillers.com\/blog\/#\/schema\/person\/254623724cef6aaeb7d85429b71aae57"},"description":"Eine aktuelle Umfrage zeigt, dass 29 Prozent der Internetnutzer der Meinung sind, dass ihre pers\u00f6nlichen Daten im online sicher sind.","breadcrumb":{"@id":"https:\/\/skyfillers.com\/blog\/2021\/02\/01\/datensicherheit-internet-vertrauen-steigt-langsam\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skyfillers.com\/blog\/2021\/02\/01\/datensicherheit-internet-vertrauen-steigt-langsam\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skyfillers.com\/blog\/2021\/02\/01\/datensicherheit-internet-vertrauen-steigt-langsam\/#primaryimage","url":"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2021\/01\/glenn-carstens-peters-npxXWgQ33ZQ-unsplash.jpg","contentUrl":"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2021\/01\/glenn-carstens-peters-npxXWgQ33ZQ-unsplash.jpg","width":1600,"height":1064,"caption":"Datensicherheit im Internet: Vertrauen der Nutzer steigt langsam"},{"@type":"BreadcrumbList","@id":"https:\/\/skyfillers.com\/blog\/2021\/02\/01\/datensicherheit-internet-vertrauen-steigt-langsam\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/skyfillers.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Datensicherheit im Internet: Vertrauen der Nutzer steigt langsam"}]},{"@type":"WebSite","@id":"https:\/\/skyfillers.com\/blog\/#website","url":"https:\/\/skyfillers.com\/blog\/","name":"Skyfillers Blog","description":"Informationen zu E-Mail, Backup, Hosting und mehr.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skyfillers.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/skyfillers.com\/blog\/#\/schema\/person\/254623724cef6aaeb7d85429b71aae57","name":"Dirk Siebels","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g","caption":"Dirk Siebels"},"url":"https:\/\/skyfillers.com\/blog\/author\/dirk\/"}]}},"_links":{"self":[{"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/posts\/4321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/comments?post=4321"}],"version-history":[{"count":2,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/posts\/4321\/revisions"}],"predecessor-version":[{"id":4323,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/posts\/4321\/revisions\/4323"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/media\/4320"}],"wp:attachment":[{"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/media?parent=4321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/categories?post=4321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/tags?post=4321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}