{"id":4075,"date":"2020-04-02T10:06:18","date_gmt":"2020-04-02T08:06:18","guid":{"rendered":"https:\/\/www.skyfillers.com\/blog\/?p=4075"},"modified":"2020-05-04T12:04:15","modified_gmt":"2020-05-04T10:04:15","slug":"corona-und-cybercrime-gefahren-krise","status":"publish","type":"post","link":"https:\/\/skyfillers.com\/blog\/2020\/04\/02\/corona-und-cybercrime-gefahren-krise\/","title":{"rendered":"Corona und Cybercrime \u2013 diese Gefahren lauern in der Krise"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Die wenigsten Computernutzer d\u00fcrften sich dar\u00fcber freuen, die Worte Corona und Cybercrime in einem Satz zu lesen. Leider gibt es in den vergangenen Wochen jedoch immer mehr Nachrichten \u00fcber Cyber-Kriminelle, die die aktuelle Lage ausnutzen. Dazu geh\u00f6ren eher harmlose Versuche, virtuelle Besprechungen <a href=\"https:\/\/www.sueddeutsche.de\/digital\/schadsoftware-zoom-video-software-kritik-1.4865024\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"\u00fcber Plattformen wie Zoom zu hacken (\u00f6ffnet in neuem Tab)\">\u00fcber Plattformen wie Zoom zu hacken<\/a>, aber auch raffinierte Betrugsversuche.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein Grund daf\u00fcr ist sicher die Tatsache, dass viele Angestellte von zu Hause aus arbeiten m\u00fcssen. Bei Unternehmen, die nicht darauf vorbereitet waren, kann das zu ernsten Problemen im Bereich der IT-Sicherheit f\u00fchren. Oft sind Mitarbeiter sogar dazu gezwungen, E-Mails von ihren privaten Konten zu verschicken. Nicht an jedem Arbeitsplatz ist es schlie\u00dflich selbstverst\u00e4ndlich, dass man auch von au\u00dferhalb des B\u00fcros Zugriff auf seine beruflichen E-Mails hat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In den vergangenen Wochen haben Experten festgestellt, dass Cyber-Kriminelle ihr Verhalten schnell ver\u00e4ndert haben. Unter anderem ist der Prozentsatz an b\u00f6sartigen E-Mails, die auf das Coronavirus Bezug nehmen, enorm gestiegen. Es scheint also, als ob Hacker die Pandemie f\u00fcr ihre eigenen Zwecke nutzen wollen. Das ist aus zwei Gr\u00fcnden erfolgversprechend. Zum einen sind aktuell viele Menschen um ihre Gesundheit besorgt, zum anderen machen sie sich <a href=\"https:\/\/www.stuttgarter-nachrichten.de\/inhalt.handel-in-der-corona-krise-historisch-schlechte-konsumlaune-sinkt-weiter.699bfd72-d36b-47ae-890e-fc32e26cd7ee.html\" target=\"_blank\" rel=\"noreferrer noopener\">Sorgen um ihr Einkommen<\/a> oder um das <a href=\"https:\/\/www.allesumsgeld.de\/mintos-und-corona\/\" target=\"_blank\" rel=\"noreferrer noopener\">angelegte Kapital<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Beispiele f\u00fcr Corona und Cybercrime<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Beispiele daf\u00fcr gibt es schon jetzt einige. Unter anderem geben sich Hacker als Mitglieder der WHO aus und bitten per E-Mail um eine Spende. Diese soll nat\u00fcrlich zum Bek\u00e4mpfen der Pandemie eingesetzt werden \u2013&nbsp;zumindest kann man das in der E-Mail lesen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dar\u00fcber hinaus tauchen vermehrt E-Mails auf, in denen vermeintlich Produkte angeboten werden, die aktuell besonders gefragt sind. Neben Desinfektionsmitteln oder Handschuhen z\u00e4hlen dazu nat\u00fcrlich auch Schutzmasken. Die aktuellen Diskussionen um eine m\u00f6gliche Pflicht zum Tragen solcher Masken in der \u00d6ffentlichkeit d\u00fcrften sicher zu noch mehr E-Mails dieser Art f\u00fchren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In der Regel geht es bei solchen E-Mails nicht darum, die Nutzer direkt zu Bestellungen zu veranlassen, die dann nicht erf\u00fcllt werden. Stattdessen sollen die Empf\u00e4nger auf bestimmte Websites gelockt werden. Das kann verschiedene Zwecke haben. F\u00fcr Computernutzer besonders gef\u00e4hrlich wird es, wenn auf der jeweiligen Seite schadhafter Code lauert, der auf dem eigenen PC installiert wird, ohne dass man es merkt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Zu guter Letzt gibt es auch immer mehr E-Mails mit Anh\u00e4ngen, in denen die Beziehung zwischen Corona und Cybercrime deutlich wird. Viele Menschen sind derzeit besorgt um ihre eigene Gesundheit oder um die von Familienangeh\u00f6rigen. Wenn gut getarnte E-Mails dann vermeintliche Anh\u00e4nge mit Informationen \u00fcber &#8222;Corona&#8220; oder &#8222;Covid-19&#8220; erhalten, ist es relativ wahrscheinlich, dass diese Dateien ge\u00f6ffnet werden. Das kann jedoch schnell dazu f\u00fchren, dass der eigene Computer mit schadhafter Software infiziert wird.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alles in allem sollte man also auch in Zeiten der aktuellen Pandemie sehr vorsichtig sein. F\u00fcr Unternehmen, die ihren Mitarbeitern einen besonders hochwertigen Schutz vor betr\u00fcgerischen E-Mails bieten wollen, gibt es eine Reihe von M\u00f6glichkeiten. Besonders umfangreich lassen sich Postf\u00e4cher zum Beispiel mit einem Dienst wie <a href=\"https:\/\/www.skyfillers.com\/blog\/2020\/03\/12\/4-fakten-advanced-threat-protection\/\">Advanced Threat Protection<\/a> (ATP) von Skyfillers sichern. Mehr Informationen zur Funktionsweise <a href=\"https:\/\/www.skyfillers.com\/de\/produkte\/e-mail\/advanced-threat-protection.html\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"gibt es hier (\u00f6ffnet in neuem Tab)\">gibt es hier<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die wenigsten Computernutzer d\u00fcrften sich dar\u00fcber freuen, die Worte Corona und Cybercrime in einem Satz zu lesen. Leider gibt es in den vergangenen Wochen jedoch immer mehr Nachrichten \u00fcber Cyber-Kriminelle, die die aktuelle Lage ausnutzen. Dazu geh\u00f6ren eher harmlose Versuche, virtuelle Besprechungen \u00fcber Plattformen wie Zoom zu hacken, aber auch raffinierte Betrugsversuche. Ein Grund daf\u00fcr &hellip;<\/p>\n","protected":false},"author":2,"featured_media":4074,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[22],"tags":[],"class_list":["post-4075","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Corona und Cybercrime \u2013 diese Gefahren lauern in der Krise<\/title>\n<meta name=\"description\" content=\"Die wenigsten Computernutzer freuen sich dar\u00fcber, die Worte Corona und Cybercrime zu lesen. Leider nutzen immer mehr Cyber-Kriminelle die Lage aus.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skyfillers.com\/blog\/2020\/04\/02\/corona-und-cybercrime-gefahren-krise\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Corona und Cybercrime \u2013 diese Gefahren lauern in der Krise\" \/>\n<meta property=\"og:description\" content=\"Die wenigsten Computernutzer freuen sich dar\u00fcber, die Worte Corona und Cybercrime zu lesen. Leider nutzen immer mehr Cyber-Kriminelle die Lage aus.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skyfillers.com\/blog\/2020\/04\/02\/corona-und-cybercrime-gefahren-krise\/\" \/>\n<meta property=\"og:site_name\" content=\"Skyfillers Blog\" \/>\n<meta property=\"article:published_time\" content=\"2020-04-02T08:06:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-04T10:04:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2020\/04\/woman-in-black-coat-and-face-standing-on-street-3983428.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dirk Siebels\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dirk Siebels\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2020\\\/04\\\/02\\\/corona-und-cybercrime-gefahren-krise\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2020\\\/04\\\/02\\\/corona-und-cybercrime-gefahren-krise\\\/\"},\"author\":{\"name\":\"Dirk Siebels\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/#\\\/schema\\\/person\\\/254623724cef6aaeb7d85429b71aae57\"},\"headline\":\"Corona und Cybercrime \u2013 diese Gefahren lauern in der Krise\",\"datePublished\":\"2020-04-02T08:06:18+00:00\",\"dateModified\":\"2020-05-04T10:04:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2020\\\/04\\\/02\\\/corona-und-cybercrime-gefahren-krise\\\/\"},\"wordCount\":530,\"image\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2020\\\/04\\\/02\\\/corona-und-cybercrime-gefahren-krise\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/woman-in-black-coat-and-face-standing-on-street-3983428.jpg\",\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2020\\\/04\\\/02\\\/corona-und-cybercrime-gefahren-krise\\\/\",\"url\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2020\\\/04\\\/02\\\/corona-und-cybercrime-gefahren-krise\\\/\",\"name\":\"Corona und Cybercrime \u2013 diese Gefahren lauern in der Krise\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2020\\\/04\\\/02\\\/corona-und-cybercrime-gefahren-krise\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2020\\\/04\\\/02\\\/corona-und-cybercrime-gefahren-krise\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/woman-in-black-coat-and-face-standing-on-street-3983428.jpg\",\"datePublished\":\"2020-04-02T08:06:18+00:00\",\"dateModified\":\"2020-05-04T10:04:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/#\\\/schema\\\/person\\\/254623724cef6aaeb7d85429b71aae57\"},\"description\":\"Die wenigsten Computernutzer freuen sich dar\u00fcber, die Worte Corona und Cybercrime zu lesen. Leider nutzen immer mehr Cyber-Kriminelle die Lage aus.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2020\\\/04\\\/02\\\/corona-und-cybercrime-gefahren-krise\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2020\\\/04\\\/02\\\/corona-und-cybercrime-gefahren-krise\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2020\\\/04\\\/02\\\/corona-und-cybercrime-gefahren-krise\\\/#primaryimage\",\"url\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/woman-in-black-coat-and-face-standing-on-street-3983428.jpg\",\"contentUrl\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/woman-in-black-coat-and-face-standing-on-street-3983428.jpg\",\"width\":1600,\"height\":1067,\"caption\":\"Corona und Cybercrime \u2013 diese Gefahren lauern in der Krise\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2020\\\/04\\\/02\\\/corona-und-cybercrime-gefahren-krise\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Corona und Cybercrime \u2013 diese Gefahren lauern in der Krise\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/\",\"name\":\"Skyfillers Blog\",\"description\":\"Informationen zu E-Mail, Backup, Hosting und mehr.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/#\\\/schema\\\/person\\\/254623724cef6aaeb7d85429b71aae57\",\"name\":\"Dirk Siebels\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g\",\"caption\":\"Dirk Siebels\"},\"url\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/author\\\/dirk\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Corona und Cybercrime \u2013 diese Gefahren lauern in der Krise","description":"Die wenigsten Computernutzer freuen sich dar\u00fcber, die Worte Corona und Cybercrime zu lesen. Leider nutzen immer mehr Cyber-Kriminelle die Lage aus.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skyfillers.com\/blog\/2020\/04\/02\/corona-und-cybercrime-gefahren-krise\/","og_locale":"de_DE","og_type":"article","og_title":"Corona und Cybercrime \u2013 diese Gefahren lauern in der Krise","og_description":"Die wenigsten Computernutzer freuen sich dar\u00fcber, die Worte Corona und Cybercrime zu lesen. Leider nutzen immer mehr Cyber-Kriminelle die Lage aus.","og_url":"https:\/\/skyfillers.com\/blog\/2020\/04\/02\/corona-und-cybercrime-gefahren-krise\/","og_site_name":"Skyfillers Blog","article_published_time":"2020-04-02T08:06:18+00:00","article_modified_time":"2020-05-04T10:04:15+00:00","og_image":[{"width":1600,"height":1067,"url":"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2020\/04\/woman-in-black-coat-and-face-standing-on-street-3983428.jpg","type":"image\/jpeg"}],"author":"Dirk Siebels","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Dirk Siebels","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/skyfillers.com\/blog\/2020\/04\/02\/corona-und-cybercrime-gefahren-krise\/#article","isPartOf":{"@id":"https:\/\/skyfillers.com\/blog\/2020\/04\/02\/corona-und-cybercrime-gefahren-krise\/"},"author":{"name":"Dirk Siebels","@id":"https:\/\/skyfillers.com\/blog\/#\/schema\/person\/254623724cef6aaeb7d85429b71aae57"},"headline":"Corona und Cybercrime \u2013 diese Gefahren lauern in der Krise","datePublished":"2020-04-02T08:06:18+00:00","dateModified":"2020-05-04T10:04:15+00:00","mainEntityOfPage":{"@id":"https:\/\/skyfillers.com\/blog\/2020\/04\/02\/corona-und-cybercrime-gefahren-krise\/"},"wordCount":530,"image":{"@id":"https:\/\/skyfillers.com\/blog\/2020\/04\/02\/corona-und-cybercrime-gefahren-krise\/#primaryimage"},"thumbnailUrl":"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2020\/04\/woman-in-black-coat-and-face-standing-on-street-3983428.jpg","inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/skyfillers.com\/blog\/2020\/04\/02\/corona-und-cybercrime-gefahren-krise\/","url":"https:\/\/skyfillers.com\/blog\/2020\/04\/02\/corona-und-cybercrime-gefahren-krise\/","name":"Corona und Cybercrime \u2013 diese Gefahren lauern in der Krise","isPartOf":{"@id":"https:\/\/skyfillers.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skyfillers.com\/blog\/2020\/04\/02\/corona-und-cybercrime-gefahren-krise\/#primaryimage"},"image":{"@id":"https:\/\/skyfillers.com\/blog\/2020\/04\/02\/corona-und-cybercrime-gefahren-krise\/#primaryimage"},"thumbnailUrl":"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2020\/04\/woman-in-black-coat-and-face-standing-on-street-3983428.jpg","datePublished":"2020-04-02T08:06:18+00:00","dateModified":"2020-05-04T10:04:15+00:00","author":{"@id":"https:\/\/skyfillers.com\/blog\/#\/schema\/person\/254623724cef6aaeb7d85429b71aae57"},"description":"Die wenigsten Computernutzer freuen sich dar\u00fcber, die Worte Corona und Cybercrime zu lesen. Leider nutzen immer mehr Cyber-Kriminelle die Lage aus.","breadcrumb":{"@id":"https:\/\/skyfillers.com\/blog\/2020\/04\/02\/corona-und-cybercrime-gefahren-krise\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skyfillers.com\/blog\/2020\/04\/02\/corona-und-cybercrime-gefahren-krise\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skyfillers.com\/blog\/2020\/04\/02\/corona-und-cybercrime-gefahren-krise\/#primaryimage","url":"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2020\/04\/woman-in-black-coat-and-face-standing-on-street-3983428.jpg","contentUrl":"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2020\/04\/woman-in-black-coat-and-face-standing-on-street-3983428.jpg","width":1600,"height":1067,"caption":"Corona und Cybercrime \u2013 diese Gefahren lauern in der Krise"},{"@type":"BreadcrumbList","@id":"https:\/\/skyfillers.com\/blog\/2020\/04\/02\/corona-und-cybercrime-gefahren-krise\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/skyfillers.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Corona und Cybercrime \u2013 diese Gefahren lauern in der Krise"}]},{"@type":"WebSite","@id":"https:\/\/skyfillers.com\/blog\/#website","url":"https:\/\/skyfillers.com\/blog\/","name":"Skyfillers Blog","description":"Informationen zu E-Mail, Backup, Hosting und mehr.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skyfillers.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/skyfillers.com\/blog\/#\/schema\/person\/254623724cef6aaeb7d85429b71aae57","name":"Dirk Siebels","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g","caption":"Dirk Siebels"},"url":"https:\/\/skyfillers.com\/blog\/author\/dirk\/"}]}},"_links":{"self":[{"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/posts\/4075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/comments?post=4075"}],"version-history":[{"count":2,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/posts\/4075\/revisions"}],"predecessor-version":[{"id":4107,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/posts\/4075\/revisions\/4107"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/media\/4074"}],"wp:attachment":[{"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/media?parent=4075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/categories?post=4075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/tags?post=4075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}