{"id":3918,"date":"2019-10-14T11:25:22","date_gmt":"2019-10-14T09:25:22","guid":{"rendered":"https:\/\/www.skyfillers.com\/blog\/?p=3918"},"modified":"2019-10-14T11:25:23","modified_gmt":"2019-10-14T09:25:23","slug":"deutschlands-mittelstand-wird-digitaler","status":"publish","type":"post","link":"https:\/\/skyfillers.com\/blog\/2019\/10\/14\/deutschlands-mittelstand-wird-digitaler\/","title":{"rendered":"Abschied vom Papier: Deutschlands Mittelstand wird digitaler"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Rechnungen werden digitalisiert, Akten elektronisch archiviert, Teams arbeiten zusammen an Dokumenten von unterschiedlichen Standorten aus: Das digitale B\u00fcro erobert den Mittelstand. Schon fast jedes zweite Unternehmen setzt nicht mehr nur auf Papier, sondern verwaltet seine Dokumente digital. Gegen\u00fcber 2017 ist das ein deutlicher Anstieg: Damals setzten noch 33 Prozent auf das sogenannte Enterprise Content Management (ECM). So wird eine ganzheitliche Strategie bezeichnet, die das Erstellen, Bearbeiten und Speichern umfasst.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dabei geht es nicht mehr nur um klassische Office- oder PDF-Dateien, die jeweils bei 92 Prozent der Unternehmen im Mittelstand digital organisiert werden. Dazu kommen auch Bilder (57 Prozent), Audio-Dateien (25 Prozent) oder Videos (18 Prozent). Das hat die repr\u00e4sentative Studie \u201eDigital Office im Mittelstand 2019\u201c von Bitkom Research im Auftrag des Digitalverbands Bitkom unter 613 Unternehmen mit 20 bis 499 Mitarbeitern ergeben.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201eECM-L\u00f6sungen bilden die wichtigste Grundlage f\u00fcr die Digitalisierung von B\u00fcro- und Verwaltungsprozessen\u201c, sagt Nils Britze, Bereichsleiter Digitale Gesch\u00e4ftsprozesse bei Bitkom. \u201eDadurch erhalten Unternehmen Unterst\u00fctzung beim effizienten Erfassen, Ablegen und Wiederauffinden von Dokumenten, bei der Abwicklung dokumentenbasierter Prozesse sowie bei der Einhaltung rechtlicher Vorgaben. Es ist erfreulich, dass der Mittelstand den Weg in Richtung des digitalen B\u00fcros beschritten hat.\u201c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das digitale B\u00fcro kommt dabei zunehmend aus der Cloud. Mehr als jedes zweite Unternehmen (58 Prozent) verwaltet seine digitalen Dokumente mittlerweile dort. Die Zahl der Unternehmen, die ihre ECM-Software im eigenen Unternehmen (\u201eon premise\u201c) betreiben, ging im gleichen Zeitraum von 59 Prozent auf 44 Prozent zur\u00fcck.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201eVor allem f\u00fcr den Mittelstand bietet die Dokumentenverwaltung und -Organisation aus der Cloud gro\u00dfes Potenzial, da IT-Ressourcen hier besonders knapp sind\u201c, betont Britze. \u201eZudem bringt dieser Weg viele Vorteile mit sich: So werden nicht nur IT-Kosten gesenkt, sondern auch die Sicherheit erh\u00f6ht: Die Cloud \u2013 \u00f6ffentlich wie privat \u2013 wird bei professionellen Dienstleistern meist wesentlich besser gesch\u00fctzt als bei internen IT-L\u00f6sungen.\u201c<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der komplette Studienbericht&nbsp;<strong>\u201eDigital Office im Mittelstand\u201c<\/strong>&nbsp;wird am 22. Oktober ver\u00f6ffentlicht und ist ab diesem Tag unter&nbsp;<a href=\"http:\/\/www.bitkom.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.bitkom.org<\/a>&nbsp;abrufbar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rechnungen werden digitalisiert, Akten elektronisch archiviert, Teams arbeiten zusammen an Dokumenten von unterschiedlichen Standorten aus: Das digitale B\u00fcro erobert den Mittelstand. Schon fast jedes zweite Unternehmen setzt nicht mehr nur auf Papier, sondern verwaltet seine Dokumente digital. Gegen\u00fcber 2017 ist das ein deutlicher Anstieg: Damals setzten noch 33 Prozent auf das sogenannte Enterprise Content Management &hellip;<\/p>\n","protected":false},"author":2,"featured_media":3917,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[22],"tags":[],"class_list":["post-3918","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Abschied vom Papier: Deutschlands Mittelstand wird digitaler<\/title>\n<meta name=\"description\" content=\"Das digitale B\u00fcro erobert den Mittelstand: Schon fast jedes zweite Unternehmen setzt nicht mehr nur auf Papier, sondern verwaltet seine Dokumente digital.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skyfillers.com\/blog\/2019\/10\/14\/deutschlands-mittelstand-wird-digitaler\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abschied vom Papier: Deutschlands Mittelstand wird digitaler\" \/>\n<meta property=\"og:description\" content=\"Das digitale B\u00fcro erobert den Mittelstand: Schon fast jedes zweite Unternehmen setzt nicht mehr nur auf Papier, sondern verwaltet seine Dokumente digital.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skyfillers.com\/blog\/2019\/10\/14\/deutschlands-mittelstand-wird-digitaler\/\" \/>\n<meta property=\"og:site_name\" content=\"Skyfillers Blog\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-14T09:25:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-14T09:25:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2019\/10\/business-2846221_1920.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dirk Siebels\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dirk Siebels\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2019\\\/10\\\/14\\\/deutschlands-mittelstand-wird-digitaler\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2019\\\/10\\\/14\\\/deutschlands-mittelstand-wird-digitaler\\\/\"},\"author\":{\"name\":\"Dirk Siebels\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/#\\\/schema\\\/person\\\/254623724cef6aaeb7d85429b71aae57\"},\"headline\":\"Abschied vom Papier: Deutschlands Mittelstand wird digitaler\",\"datePublished\":\"2019-10-14T09:25:22+00:00\",\"dateModified\":\"2019-10-14T09:25:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2019\\\/10\\\/14\\\/deutschlands-mittelstand-wird-digitaler\\\/\"},\"wordCount\":333,\"image\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2019\\\/10\\\/14\\\/deutschlands-mittelstand-wird-digitaler\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/business-2846221_1920.jpg\",\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2019\\\/10\\\/14\\\/deutschlands-mittelstand-wird-digitaler\\\/\",\"url\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2019\\\/10\\\/14\\\/deutschlands-mittelstand-wird-digitaler\\\/\",\"name\":\"Abschied vom Papier: Deutschlands Mittelstand wird digitaler\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2019\\\/10\\\/14\\\/deutschlands-mittelstand-wird-digitaler\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2019\\\/10\\\/14\\\/deutschlands-mittelstand-wird-digitaler\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/business-2846221_1920.jpg\",\"datePublished\":\"2019-10-14T09:25:22+00:00\",\"dateModified\":\"2019-10-14T09:25:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/#\\\/schema\\\/person\\\/254623724cef6aaeb7d85429b71aae57\"},\"description\":\"Das digitale B\u00fcro erobert den Mittelstand: Schon fast jedes zweite Unternehmen setzt nicht mehr nur auf Papier, sondern verwaltet seine Dokumente digital.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2019\\\/10\\\/14\\\/deutschlands-mittelstand-wird-digitaler\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2019\\\/10\\\/14\\\/deutschlands-mittelstand-wird-digitaler\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2019\\\/10\\\/14\\\/deutschlands-mittelstand-wird-digitaler\\\/#primaryimage\",\"url\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/business-2846221_1920.jpg\",\"contentUrl\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/10\\\/business-2846221_1920.jpg\",\"width\":1600,\"height\":1067,\"caption\":\"Abschied vom Papier: Deutschlands Mittelstand wird digitaler\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2019\\\/10\\\/14\\\/deutschlands-mittelstand-wird-digitaler\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abschied vom Papier: Deutschlands Mittelstand wird digitaler\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/\",\"name\":\"Skyfillers Blog\",\"description\":\"Informationen zu E-Mail, Backup, Hosting und mehr.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/#\\\/schema\\\/person\\\/254623724cef6aaeb7d85429b71aae57\",\"name\":\"Dirk Siebels\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g\",\"caption\":\"Dirk Siebels\"},\"url\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/author\\\/dirk\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abschied vom Papier: Deutschlands Mittelstand wird digitaler","description":"Das digitale B\u00fcro erobert den Mittelstand: Schon fast jedes zweite Unternehmen setzt nicht mehr nur auf Papier, sondern verwaltet seine Dokumente digital.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skyfillers.com\/blog\/2019\/10\/14\/deutschlands-mittelstand-wird-digitaler\/","og_locale":"de_DE","og_type":"article","og_title":"Abschied vom Papier: Deutschlands Mittelstand wird digitaler","og_description":"Das digitale B\u00fcro erobert den Mittelstand: Schon fast jedes zweite Unternehmen setzt nicht mehr nur auf Papier, sondern verwaltet seine Dokumente digital.","og_url":"https:\/\/skyfillers.com\/blog\/2019\/10\/14\/deutschlands-mittelstand-wird-digitaler\/","og_site_name":"Skyfillers Blog","article_published_time":"2019-10-14T09:25:22+00:00","article_modified_time":"2019-10-14T09:25:23+00:00","og_image":[{"width":1600,"height":1067,"url":"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2019\/10\/business-2846221_1920.jpg","type":"image\/jpeg"}],"author":"Dirk Siebels","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Dirk Siebels","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/skyfillers.com\/blog\/2019\/10\/14\/deutschlands-mittelstand-wird-digitaler\/#article","isPartOf":{"@id":"https:\/\/skyfillers.com\/blog\/2019\/10\/14\/deutschlands-mittelstand-wird-digitaler\/"},"author":{"name":"Dirk Siebels","@id":"https:\/\/skyfillers.com\/blog\/#\/schema\/person\/254623724cef6aaeb7d85429b71aae57"},"headline":"Abschied vom Papier: Deutschlands Mittelstand wird digitaler","datePublished":"2019-10-14T09:25:22+00:00","dateModified":"2019-10-14T09:25:23+00:00","mainEntityOfPage":{"@id":"https:\/\/skyfillers.com\/blog\/2019\/10\/14\/deutschlands-mittelstand-wird-digitaler\/"},"wordCount":333,"image":{"@id":"https:\/\/skyfillers.com\/blog\/2019\/10\/14\/deutschlands-mittelstand-wird-digitaler\/#primaryimage"},"thumbnailUrl":"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2019\/10\/business-2846221_1920.jpg","inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/skyfillers.com\/blog\/2019\/10\/14\/deutschlands-mittelstand-wird-digitaler\/","url":"https:\/\/skyfillers.com\/blog\/2019\/10\/14\/deutschlands-mittelstand-wird-digitaler\/","name":"Abschied vom Papier: Deutschlands Mittelstand wird digitaler","isPartOf":{"@id":"https:\/\/skyfillers.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skyfillers.com\/blog\/2019\/10\/14\/deutschlands-mittelstand-wird-digitaler\/#primaryimage"},"image":{"@id":"https:\/\/skyfillers.com\/blog\/2019\/10\/14\/deutschlands-mittelstand-wird-digitaler\/#primaryimage"},"thumbnailUrl":"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2019\/10\/business-2846221_1920.jpg","datePublished":"2019-10-14T09:25:22+00:00","dateModified":"2019-10-14T09:25:23+00:00","author":{"@id":"https:\/\/skyfillers.com\/blog\/#\/schema\/person\/254623724cef6aaeb7d85429b71aae57"},"description":"Das digitale B\u00fcro erobert den Mittelstand: Schon fast jedes zweite Unternehmen setzt nicht mehr nur auf Papier, sondern verwaltet seine Dokumente digital.","breadcrumb":{"@id":"https:\/\/skyfillers.com\/blog\/2019\/10\/14\/deutschlands-mittelstand-wird-digitaler\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skyfillers.com\/blog\/2019\/10\/14\/deutschlands-mittelstand-wird-digitaler\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skyfillers.com\/blog\/2019\/10\/14\/deutschlands-mittelstand-wird-digitaler\/#primaryimage","url":"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2019\/10\/business-2846221_1920.jpg","contentUrl":"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2019\/10\/business-2846221_1920.jpg","width":1600,"height":1067,"caption":"Abschied vom Papier: Deutschlands Mittelstand wird digitaler"},{"@type":"BreadcrumbList","@id":"https:\/\/skyfillers.com\/blog\/2019\/10\/14\/deutschlands-mittelstand-wird-digitaler\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/skyfillers.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Abschied vom Papier: Deutschlands Mittelstand wird digitaler"}]},{"@type":"WebSite","@id":"https:\/\/skyfillers.com\/blog\/#website","url":"https:\/\/skyfillers.com\/blog\/","name":"Skyfillers Blog","description":"Informationen zu E-Mail, Backup, Hosting und mehr.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skyfillers.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/skyfillers.com\/blog\/#\/schema\/person\/254623724cef6aaeb7d85429b71aae57","name":"Dirk Siebels","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g","caption":"Dirk Siebels"},"url":"https:\/\/skyfillers.com\/blog\/author\/dirk\/"}]}},"_links":{"self":[{"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/posts\/3918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/comments?post=3918"}],"version-history":[{"count":1,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/posts\/3918\/revisions"}],"predecessor-version":[{"id":3919,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/posts\/3918\/revisions\/3919"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/media\/3917"}],"wp:attachment":[{"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/media?parent=3918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/categories?post=3918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/tags?post=3918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}