{"id":3876,"date":"2019-08-29T10:21:06","date_gmt":"2019-08-29T08:21:06","guid":{"rendered":"https:\/\/www.skyfillers.com\/blog\/?p=3876"},"modified":"2019-08-29T10:21:07","modified_gmt":"2019-08-29T08:21:07","slug":"ende-von-windows-7","status":"publish","type":"post","link":"https:\/\/skyfillers.com\/blog\/2019\/08\/29\/ende-von-windows-7\/","title":{"rendered":"Ende von Windows 7 im Januar 2020"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Das Ende von Windows 7 ist absehbar: Am 14. Januar 2020 m\u00fcssen viele Nutzer weltweit von ihrem geliebten Betriebssystem Abschied nehmen. Ab diesem Datum wird das System nach Angaben von Microsoft nicht mehr aktualisiert oder unterst\u00fctzt. Nat\u00fcrlich kann das Betriebssystem auch danach noch genutzt werden, allerdings d\u00fcrfte es sehr schnell eine Reihe von Sicherheitsl\u00fccken geben, f\u00fcr die Microsoft dann nicht mehr zust\u00e4ndig ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Schon im Jahr 2015 hatte Microsoft bekanntgegeben, dass keine neuen Funktionen mehr zu Windows 7 hinzugef\u00fcgt werden. Damit war der komplette Stopp des Supports bereits absehbar, auch wenn es daf\u00fcr noch kein genaues Datum gab. Viele Unternehmen, in denen dieses Betriebssystem noch immer verwendet wird, h\u00e4tten damals schon hellh\u00f6rig werden sollen. Sp\u00e4testens jetzt wird es aber Zeit, eine Umstellung auf eine aktuellere Version von Windows zu planen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Ende von Windows 7 muss kein Problem sein<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Wie gro\u00df das Problem in der Praxis ist, wird bei einem Blick auf die Zahlen deutlich. Die russische IT-Sicherheitsfirma Kaspersky hat vor einigen Tagen <a href=\"https:\/\/usa.kaspersky.com\/about\/press-releases\/2019_consumers-still-use-unsupported-and-near-end-of-life-os\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"eine Pressemitteilung ver\u00f6ffentlicht (\u00f6ffnet in neuem Tab)\">eine Pressemitteilung ver\u00f6ffentlicht<\/a>, in der betont wird, dass mehr als 40 Prozent von kleinen und mittelst\u00e4ndischen Unternehmen (KMUs) noch immer Windows 7 verwenden. Auch bei privaten Nutzern ist dieses System noch weit verbreitet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Ende des Supports f\u00fcr das Betriebssystem sorgt also f\u00fcr Handlungsbedarf. Die Entwickler bei Microsoft befinden sich in einem st\u00e4ndigen Wettr\u00fcsten mit Hackern und anderen Kriminellen, deshalb werden immer wieder Updates ver\u00f6ffentlicht. Diese sorgen daf\u00fcr, dass ein Betriebssystem sicher bleibt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durch das bevorstehende Ende von Windows 7 werden viele Unternehmen nun zum Handeln gezwungen. Wenn Verantwortliche daf\u00fcr sorgen wollen, dass keine Unbefugten Zugriff auf interne Daten erhalten, sollte die Umstellung auf eine aktuellere Version sp\u00e4testens jetzt geplant werden. F\u00fcr die einzelnen Mitarbeiter hei\u00dft das jedoch in der Regel nicht, dass es enorme Neuerungen gibt. Die gro\u00dfe Mehrzahl der bislang genutzten Systeme laufen schlie\u00dflich auch unter j\u00fcngeren Windows-Versionen. Zudem ist es in diesem Zuge sinnvoll, sich \u00fcber ein m\u00f6gliches <a href=\"https:\/\/www.skyfillers.com\/de\/produkte\/e-mail\/hosted-exchange.html\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Outsourcing von bestimmten Diensten (\u00f6ffnet in neuem Tab)\">Outsourcing von bestimmten Diensten<\/a> Gedanken zu machen. So wird die Aufgabe zu einer echten Chance.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Ende von Windows 7 ist absehbar: Am 14. Januar 2020 m\u00fcssen viele Nutzer weltweit von ihrem geliebten Betriebssystem Abschied nehmen. Ab diesem Datum wird das System nach Angaben von Microsoft nicht mehr aktualisiert oder unterst\u00fctzt. Nat\u00fcrlich kann das Betriebssystem auch danach noch genutzt werden, allerdings d\u00fcrfte es sehr schnell eine Reihe von Sicherheitsl\u00fccken geben, &hellip;<\/p>\n","protected":false},"author":2,"featured_media":3875,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[22],"tags":[],"class_list":["post-3876","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ende von Windows 7 ist jetzt f\u00fcr Januar 2020 geplant<\/title>\n<meta name=\"description\" content=\"Das Ende von Windows 7 ist absehbar: Am 14. Januar 2020 m\u00fcssen viele Nutzer weltweit von ihrem geliebten Betriebssystem Abschied nehmen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skyfillers.com\/blog\/2019\/08\/29\/ende-von-windows-7\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ende von Windows 7 ist jetzt f\u00fcr Januar 2020 geplant\" \/>\n<meta property=\"og:description\" content=\"Das Ende von Windows 7 ist absehbar: Am 14. Januar 2020 m\u00fcssen viele Nutzer weltweit von ihrem geliebten Betriebssystem Abschied nehmen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skyfillers.com\/blog\/2019\/08\/29\/ende-von-windows-7\/\" \/>\n<meta property=\"og:site_name\" content=\"Skyfillers Blog\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-29T08:21:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-29T08:21:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2019\/08\/office-2009693_1920.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dirk Siebels\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dirk Siebels\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2019\\\/08\\\/29\\\/ende-von-windows-7\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2019\\\/08\\\/29\\\/ende-von-windows-7\\\/\"},\"author\":{\"name\":\"Dirk Siebels\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/#\\\/schema\\\/person\\\/254623724cef6aaeb7d85429b71aae57\"},\"headline\":\"Ende von Windows 7 im Januar 2020\",\"datePublished\":\"2019-08-29T08:21:06+00:00\",\"dateModified\":\"2019-08-29T08:21:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2019\\\/08\\\/29\\\/ende-von-windows-7\\\/\"},\"wordCount\":352,\"image\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2019\\\/08\\\/29\\\/ende-von-windows-7\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/office-2009693_1920.jpg\",\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2019\\\/08\\\/29\\\/ende-von-windows-7\\\/\",\"url\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2019\\\/08\\\/29\\\/ende-von-windows-7\\\/\",\"name\":\"Ende von Windows 7 ist jetzt f\u00fcr Januar 2020 geplant\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2019\\\/08\\\/29\\\/ende-von-windows-7\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2019\\\/08\\\/29\\\/ende-von-windows-7\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/office-2009693_1920.jpg\",\"datePublished\":\"2019-08-29T08:21:06+00:00\",\"dateModified\":\"2019-08-29T08:21:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/#\\\/schema\\\/person\\\/254623724cef6aaeb7d85429b71aae57\"},\"description\":\"Das Ende von Windows 7 ist absehbar: Am 14. Januar 2020 m\u00fcssen viele Nutzer weltweit von ihrem geliebten Betriebssystem Abschied nehmen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2019\\\/08\\\/29\\\/ende-von-windows-7\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2019\\\/08\\\/29\\\/ende-von-windows-7\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2019\\\/08\\\/29\\\/ende-von-windows-7\\\/#primaryimage\",\"url\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/office-2009693_1920.jpg\",\"contentUrl\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/office-2009693_1920.jpg\",\"width\":1600,\"height\":1067,\"caption\":\"Ende von Windows 7 im Januar 2020\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2019\\\/08\\\/29\\\/ende-von-windows-7\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ende von Windows 7 im Januar 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/\",\"name\":\"Skyfillers Blog\",\"description\":\"Informationen zu E-Mail, Backup, Hosting und mehr.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/#\\\/schema\\\/person\\\/254623724cef6aaeb7d85429b71aae57\",\"name\":\"Dirk Siebels\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g\",\"caption\":\"Dirk Siebels\"},\"url\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/author\\\/dirk\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ende von Windows 7 ist jetzt f\u00fcr Januar 2020 geplant","description":"Das Ende von Windows 7 ist absehbar: Am 14. Januar 2020 m\u00fcssen viele Nutzer weltweit von ihrem geliebten Betriebssystem Abschied nehmen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skyfillers.com\/blog\/2019\/08\/29\/ende-von-windows-7\/","og_locale":"de_DE","og_type":"article","og_title":"Ende von Windows 7 ist jetzt f\u00fcr Januar 2020 geplant","og_description":"Das Ende von Windows 7 ist absehbar: Am 14. Januar 2020 m\u00fcssen viele Nutzer weltweit von ihrem geliebten Betriebssystem Abschied nehmen.","og_url":"https:\/\/skyfillers.com\/blog\/2019\/08\/29\/ende-von-windows-7\/","og_site_name":"Skyfillers Blog","article_published_time":"2019-08-29T08:21:06+00:00","article_modified_time":"2019-08-29T08:21:07+00:00","og_image":[{"width":1600,"height":1067,"url":"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2019\/08\/office-2009693_1920.jpg","type":"image\/jpeg"}],"author":"Dirk Siebels","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Dirk Siebels","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/skyfillers.com\/blog\/2019\/08\/29\/ende-von-windows-7\/#article","isPartOf":{"@id":"https:\/\/skyfillers.com\/blog\/2019\/08\/29\/ende-von-windows-7\/"},"author":{"name":"Dirk Siebels","@id":"https:\/\/skyfillers.com\/blog\/#\/schema\/person\/254623724cef6aaeb7d85429b71aae57"},"headline":"Ende von Windows 7 im Januar 2020","datePublished":"2019-08-29T08:21:06+00:00","dateModified":"2019-08-29T08:21:07+00:00","mainEntityOfPage":{"@id":"https:\/\/skyfillers.com\/blog\/2019\/08\/29\/ende-von-windows-7\/"},"wordCount":352,"image":{"@id":"https:\/\/skyfillers.com\/blog\/2019\/08\/29\/ende-von-windows-7\/#primaryimage"},"thumbnailUrl":"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2019\/08\/office-2009693_1920.jpg","inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/skyfillers.com\/blog\/2019\/08\/29\/ende-von-windows-7\/","url":"https:\/\/skyfillers.com\/blog\/2019\/08\/29\/ende-von-windows-7\/","name":"Ende von Windows 7 ist jetzt f\u00fcr Januar 2020 geplant","isPartOf":{"@id":"https:\/\/skyfillers.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skyfillers.com\/blog\/2019\/08\/29\/ende-von-windows-7\/#primaryimage"},"image":{"@id":"https:\/\/skyfillers.com\/blog\/2019\/08\/29\/ende-von-windows-7\/#primaryimage"},"thumbnailUrl":"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2019\/08\/office-2009693_1920.jpg","datePublished":"2019-08-29T08:21:06+00:00","dateModified":"2019-08-29T08:21:07+00:00","author":{"@id":"https:\/\/skyfillers.com\/blog\/#\/schema\/person\/254623724cef6aaeb7d85429b71aae57"},"description":"Das Ende von Windows 7 ist absehbar: Am 14. Januar 2020 m\u00fcssen viele Nutzer weltweit von ihrem geliebten Betriebssystem Abschied nehmen.","breadcrumb":{"@id":"https:\/\/skyfillers.com\/blog\/2019\/08\/29\/ende-von-windows-7\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skyfillers.com\/blog\/2019\/08\/29\/ende-von-windows-7\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skyfillers.com\/blog\/2019\/08\/29\/ende-von-windows-7\/#primaryimage","url":"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2019\/08\/office-2009693_1920.jpg","contentUrl":"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2019\/08\/office-2009693_1920.jpg","width":1600,"height":1067,"caption":"Ende von Windows 7 im Januar 2020"},{"@type":"BreadcrumbList","@id":"https:\/\/skyfillers.com\/blog\/2019\/08\/29\/ende-von-windows-7\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/skyfillers.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Ende von Windows 7 im Januar 2020"}]},{"@type":"WebSite","@id":"https:\/\/skyfillers.com\/blog\/#website","url":"https:\/\/skyfillers.com\/blog\/","name":"Skyfillers Blog","description":"Informationen zu E-Mail, Backup, Hosting und mehr.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skyfillers.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/skyfillers.com\/blog\/#\/schema\/person\/254623724cef6aaeb7d85429b71aae57","name":"Dirk Siebels","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g","caption":"Dirk Siebels"},"url":"https:\/\/skyfillers.com\/blog\/author\/dirk\/"}]}},"_links":{"self":[{"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/posts\/3876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/comments?post=3876"}],"version-history":[{"count":1,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/posts\/3876\/revisions"}],"predecessor-version":[{"id":3877,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/posts\/3876\/revisions\/3877"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/media\/3875"}],"wp:attachment":[{"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/media?parent=3876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/categories?post=3876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/tags?post=3876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}