{"id":3671,"date":"2019-02-13T11:36:23","date_gmt":"2019-02-13T10:36:23","guid":{"rendered":"https:\/\/www.skyfillers.com\/blog\/?p=3671"},"modified":"2019-02-13T11:36:25","modified_gmt":"2019-02-13T10:36:25","slug":"cyberkriminalitaet-problem-kmus","status":"publish","type":"post","link":"https:\/\/skyfillers.com\/blog\/2019\/02\/13\/cyberkriminalitaet-problem-kmus\/","title":{"rendered":"Cyberkriminalit\u00e4t \u2013 immer gr\u00f6\u00dferes Problem f\u00fcr KMUs"},"content":{"rendered":"\n<p>Im Jahr 2018 stand Cyberkriminalit\u00e4t so stark im Fokus wie noch nie zuvor. Immer wieder gab es Schlagzeilen \u00fcber Datenlecks, besonders aggressive Varianten von Schadsoftware und vor allem \u00fcber hohe finanzielle Sch\u00e4den, unter denen viele Unternehmen leiden.<\/p>\n\n\n\n<p>Auch in diesem Jahr d\u00fcrfte sich an der Bedrohungslage wenig \u00e4ndern. Vor allem in kleinen und mittelst\u00e4ndischen Unternehmen (KMU) sollten sich die Verantwortlichen mit diesem Thema besch\u00e4ftigen. Obwohl KMUs selten im Fokus der Berichterstattung stehen, werden diese immer \u00f6fter zum Ziel von Kriminellen im Internet.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Industrie als Angriffsziel<\/h3>\n\n\n\n<p>Durch die Anbindung an das Internet und an Clouddienste sollen gerade in der Industrie viele Abl\u00e4ufe deutlich produktiver werden. Allerdings sorgt diese immer st\u00e4rkere Vernetzung zugleich daf\u00fcr, dass Unternehmen angreifbar werden. Das ist besonders dann der Fall, wenn solche Systeme ohne die n\u00f6tigen Sicherungen geplant werden oder wenn diese keinen ausreichenden Schutz bieten.<\/p>\n\n\n\n<p>Wie gro\u00df das Problem ist, zeigen die folgenden Zahlen. In den Jahren 2017 und 2018 wurden rund 70 Prozent aller Industrieunternehmen in Deutschland Opfer von Datendiebstahl, Sabotage oder Industriespionage. Der Schaden bel\u00e4uft sich nach Berechnungen von Experten auf deutlich mehr als 40 Milliarden Euro.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Probleme durch Cyberkriminalit\u00e4t immer gr\u00f6\u00dfer<\/h3>\n\n\n\n<p>Obwohl die oben genannten Zahlen schon erschreckend klingen, d\u00fcrfte das Problem in den kommenden Jahren noch weiter wachsen. Das liegt allein schon daran, dass nur etwa ein F\u00fcnftel aller deutschen Unternehmen schon digitalisiert sind \u2013\u00a0diese Quote findet sich jedenfalls im <a href=\"https:\/\/www.iwkoeln.de\/studien\/gutachten\/beitrag\/roman-bertenrath-manuel-fritsch-thorsten-lang-karl-lichtblau-agnes-ricci-thomas-schleiermacher-digital-atlas-deutschland.html\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"Digital-Atlas (\u00f6ffnet in neuem Tab)\">Digital-Atlas<\/a>, den das Institut der Deutschen Wirtschaft gemeinsam mit Google Germany erstellt hat.<\/p>\n\n\n\n<p>Noch immer gibt es in Deutschland gro\u00dfe Sorgen um die Datensicherheit, zudem ist die Versorgung mit Breitbandanschl\u00fcssen l\u00e4ngst nicht \u00fcberall abgeschlossen. Mangelnde Kompetenzen sind gerade bei KMUs ein weiteres gro\u00dfes Problem.<\/p>\n\n\n\n<p>In den n\u00e4chsten Jahren d\u00fcrfte die Digitalisierung also noch gro\u00dfe Fortschritte machen. Das ist grunds\u00e4tzlich sehr positiv, allerdings sollte der Aspekt Sicherheit bei allen L\u00f6sungen bedacht werden. Wer sich auf <a href=\"https:\/\/www.skyfillers.com\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\"spezialisierte Dienstleister (\u00f6ffnet in neuem Tab)\">spezialisierte Dienstleister<\/a> verl\u00e4sst, kann jedoch mit Cloud-Diensten in ganz unterschiedlichen Bereichen f\u00fcr effiziente Abl\u00e4ufe sorgen und auf diese Weise die Produktivit\u00e4t im Tagesgesch\u00e4ft deutlich steigern, ohne zum Opfer von Cyberkriminalit\u00e4t zu werden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im Jahr 2018 stand Cyberkriminalit\u00e4t so stark im Fokus wie noch nie zuvor. Immer wieder gab es Schlagzeilen \u00fcber Datenlecks, besonders aggressive Varianten von Schadsoftware und vor allem \u00fcber hohe finanzielle Sch\u00e4den, unter denen viele Unternehmen leiden. Auch in diesem Jahr d\u00fcrfte sich an der Bedrohungslage wenig \u00e4ndern. Vor allem in kleinen und mittelst\u00e4ndischen Unternehmen &hellip;<\/p>\n","protected":false},"author":2,"featured_media":3670,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-3671","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hosting"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cyberkriminalit\u00e4t \u2013 immer gr\u00f6\u00dferes Problem f\u00fcr KMUs<\/title>\n<meta name=\"description\" content=\"Immer wieder gab es 2018 Schlagzeilen \u00fcber Cyberkriminalit\u00e4t und vor allem \u00fcber hohe finanzielle Sch\u00e4den, unter denen viele Unternehmen leiden.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/skyfillers.com\/blog\/2019\/02\/13\/cyberkriminalitaet-problem-kmus\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cyberkriminalit\u00e4t \u2013 immer gr\u00f6\u00dferes Problem f\u00fcr KMUs\" \/>\n<meta property=\"og:description\" content=\"Immer wieder gab es 2018 Schlagzeilen \u00fcber Cyberkriminalit\u00e4t und vor allem \u00fcber hohe finanzielle Sch\u00e4den, unter denen viele Unternehmen leiden.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/skyfillers.com\/blog\/2019\/02\/13\/cyberkriminalitaet-problem-kmus\/\" \/>\n<meta property=\"og:site_name\" content=\"Skyfillers Blog\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-13T10:36:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-02-13T10:36:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2019\/02\/brainstorming-2398562_1920.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Dirk Siebels\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dirk Siebels\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2019\\\/02\\\/13\\\/cyberkriminalitaet-problem-kmus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2019\\\/02\\\/13\\\/cyberkriminalitaet-problem-kmus\\\/\"},\"author\":{\"name\":\"Dirk Siebels\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/#\\\/schema\\\/person\\\/254623724cef6aaeb7d85429b71aae57\"},\"headline\":\"Cyberkriminalit\u00e4t \u2013 immer gr\u00f6\u00dferes Problem f\u00fcr KMUs\",\"datePublished\":\"2019-02-13T10:36:23+00:00\",\"dateModified\":\"2019-02-13T10:36:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2019\\\/02\\\/13\\\/cyberkriminalitaet-problem-kmus\\\/\"},\"wordCount\":366,\"image\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2019\\\/02\\\/13\\\/cyberkriminalitaet-problem-kmus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/brainstorming-2398562_1920.jpg\",\"articleSection\":[\"Hosting\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2019\\\/02\\\/13\\\/cyberkriminalitaet-problem-kmus\\\/\",\"url\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2019\\\/02\\\/13\\\/cyberkriminalitaet-problem-kmus\\\/\",\"name\":\"Cyberkriminalit\u00e4t \u2013 immer gr\u00f6\u00dferes Problem f\u00fcr KMUs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2019\\\/02\\\/13\\\/cyberkriminalitaet-problem-kmus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2019\\\/02\\\/13\\\/cyberkriminalitaet-problem-kmus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/brainstorming-2398562_1920.jpg\",\"datePublished\":\"2019-02-13T10:36:23+00:00\",\"dateModified\":\"2019-02-13T10:36:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/#\\\/schema\\\/person\\\/254623724cef6aaeb7d85429b71aae57\"},\"description\":\"Immer wieder gab es 2018 Schlagzeilen \u00fcber Cyberkriminalit\u00e4t und vor allem \u00fcber hohe finanzielle Sch\u00e4den, unter denen viele Unternehmen leiden.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2019\\\/02\\\/13\\\/cyberkriminalitaet-problem-kmus\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2019\\\/02\\\/13\\\/cyberkriminalitaet-problem-kmus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2019\\\/02\\\/13\\\/cyberkriminalitaet-problem-kmus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/brainstorming-2398562_1920.jpg\",\"contentUrl\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/brainstorming-2398562_1920.jpg\",\"width\":1600,\"height\":1067,\"caption\":\"Cyberkriminalit\u00e4t \u2013 immer gr\u00f6\u00dferes Problem f\u00fcr KMUs\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/2019\\\/02\\\/13\\\/cyberkriminalitaet-problem-kmus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cyberkriminalit\u00e4t \u2013 immer gr\u00f6\u00dferes Problem f\u00fcr KMUs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/\",\"name\":\"Skyfillers Blog\",\"description\":\"Informationen zu E-Mail, Backup, Hosting und mehr.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/#\\\/schema\\\/person\\\/254623724cef6aaeb7d85429b71aae57\",\"name\":\"Dirk Siebels\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g\",\"caption\":\"Dirk Siebels\"},\"url\":\"https:\\\/\\\/skyfillers.com\\\/blog\\\/author\\\/dirk\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cyberkriminalit\u00e4t \u2013 immer gr\u00f6\u00dferes Problem f\u00fcr KMUs","description":"Immer wieder gab es 2018 Schlagzeilen \u00fcber Cyberkriminalit\u00e4t und vor allem \u00fcber hohe finanzielle Sch\u00e4den, unter denen viele Unternehmen leiden.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/skyfillers.com\/blog\/2019\/02\/13\/cyberkriminalitaet-problem-kmus\/","og_locale":"de_DE","og_type":"article","og_title":"Cyberkriminalit\u00e4t \u2013 immer gr\u00f6\u00dferes Problem f\u00fcr KMUs","og_description":"Immer wieder gab es 2018 Schlagzeilen \u00fcber Cyberkriminalit\u00e4t und vor allem \u00fcber hohe finanzielle Sch\u00e4den, unter denen viele Unternehmen leiden.","og_url":"https:\/\/skyfillers.com\/blog\/2019\/02\/13\/cyberkriminalitaet-problem-kmus\/","og_site_name":"Skyfillers Blog","article_published_time":"2019-02-13T10:36:23+00:00","article_modified_time":"2019-02-13T10:36:25+00:00","og_image":[{"width":1600,"height":1067,"url":"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2019\/02\/brainstorming-2398562_1920.jpg","type":"image\/jpeg"}],"author":"Dirk Siebels","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Dirk Siebels","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/skyfillers.com\/blog\/2019\/02\/13\/cyberkriminalitaet-problem-kmus\/#article","isPartOf":{"@id":"https:\/\/skyfillers.com\/blog\/2019\/02\/13\/cyberkriminalitaet-problem-kmus\/"},"author":{"name":"Dirk Siebels","@id":"https:\/\/skyfillers.com\/blog\/#\/schema\/person\/254623724cef6aaeb7d85429b71aae57"},"headline":"Cyberkriminalit\u00e4t \u2013 immer gr\u00f6\u00dferes Problem f\u00fcr KMUs","datePublished":"2019-02-13T10:36:23+00:00","dateModified":"2019-02-13T10:36:25+00:00","mainEntityOfPage":{"@id":"https:\/\/skyfillers.com\/blog\/2019\/02\/13\/cyberkriminalitaet-problem-kmus\/"},"wordCount":366,"image":{"@id":"https:\/\/skyfillers.com\/blog\/2019\/02\/13\/cyberkriminalitaet-problem-kmus\/#primaryimage"},"thumbnailUrl":"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2019\/02\/brainstorming-2398562_1920.jpg","articleSection":["Hosting"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/skyfillers.com\/blog\/2019\/02\/13\/cyberkriminalitaet-problem-kmus\/","url":"https:\/\/skyfillers.com\/blog\/2019\/02\/13\/cyberkriminalitaet-problem-kmus\/","name":"Cyberkriminalit\u00e4t \u2013 immer gr\u00f6\u00dferes Problem f\u00fcr KMUs","isPartOf":{"@id":"https:\/\/skyfillers.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/skyfillers.com\/blog\/2019\/02\/13\/cyberkriminalitaet-problem-kmus\/#primaryimage"},"image":{"@id":"https:\/\/skyfillers.com\/blog\/2019\/02\/13\/cyberkriminalitaet-problem-kmus\/#primaryimage"},"thumbnailUrl":"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2019\/02\/brainstorming-2398562_1920.jpg","datePublished":"2019-02-13T10:36:23+00:00","dateModified":"2019-02-13T10:36:25+00:00","author":{"@id":"https:\/\/skyfillers.com\/blog\/#\/schema\/person\/254623724cef6aaeb7d85429b71aae57"},"description":"Immer wieder gab es 2018 Schlagzeilen \u00fcber Cyberkriminalit\u00e4t und vor allem \u00fcber hohe finanzielle Sch\u00e4den, unter denen viele Unternehmen leiden.","breadcrumb":{"@id":"https:\/\/skyfillers.com\/blog\/2019\/02\/13\/cyberkriminalitaet-problem-kmus\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/skyfillers.com\/blog\/2019\/02\/13\/cyberkriminalitaet-problem-kmus\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/skyfillers.com\/blog\/2019\/02\/13\/cyberkriminalitaet-problem-kmus\/#primaryimage","url":"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2019\/02\/brainstorming-2398562_1920.jpg","contentUrl":"https:\/\/skyfillers.com\/blog\/wp-content\/uploads\/2019\/02\/brainstorming-2398562_1920.jpg","width":1600,"height":1067,"caption":"Cyberkriminalit\u00e4t \u2013 immer gr\u00f6\u00dferes Problem f\u00fcr KMUs"},{"@type":"BreadcrumbList","@id":"https:\/\/skyfillers.com\/blog\/2019\/02\/13\/cyberkriminalitaet-problem-kmus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/skyfillers.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Cyberkriminalit\u00e4t \u2013 immer gr\u00f6\u00dferes Problem f\u00fcr KMUs"}]},{"@type":"WebSite","@id":"https:\/\/skyfillers.com\/blog\/#website","url":"https:\/\/skyfillers.com\/blog\/","name":"Skyfillers Blog","description":"Informationen zu E-Mail, Backup, Hosting und mehr.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/skyfillers.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/skyfillers.com\/blog\/#\/schema\/person\/254623724cef6aaeb7d85429b71aae57","name":"Dirk Siebels","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/96de72e6634fd6dcd75bfe7f199ceaf0e9d1394c8de8e91dc42f49396bfdae70?s=96&d=mm&r=g","caption":"Dirk Siebels"},"url":"https:\/\/skyfillers.com\/blog\/author\/dirk\/"}]}},"_links":{"self":[{"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/posts\/3671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/comments?post=3671"}],"version-history":[{"count":1,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/posts\/3671\/revisions"}],"predecessor-version":[{"id":3672,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/posts\/3671\/revisions\/3672"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/media\/3670"}],"wp:attachment":[{"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/media?parent=3671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/categories?post=3671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/skyfillers.com\/blog\/wp-json\/wp\/v2\/tags?post=3671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}